{"id":8729,"date":"2015-04-26T17:37:58","date_gmt":"2015-04-26T16:37:58","guid":{"rendered":"http:\/\/www.jungsi.de\/?p=8729"},"modified":"2026-08-25T09:37:40","modified_gmt":"2026-08-25T07:37:40","slug":"sir-abadol-2-retro-sinclair-zx-spectrum","status":"publish","type":"post","link":"https:\/\/www.jungsi.de\/en\/sir-abadol-2-retro-sinclair-zx-spectrum\/","title":{"rendered":"Sir Ababol 2 [Retro: Sinclair ZX Spectrum]"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignright\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/04\/Sir-Abadol-II-Men\u00fc.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"223\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/04\/Sir-Abadol-II-Men\u00fc-300x223.jpg\" alt=\"Sir Abadol II - Men\u00fc\" class=\"wp-image-10502\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/04\/Sir-Abadol-II-Men\u00fc-300x223.jpg 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/04\/Sir-Abadol-II-Men\u00fc.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption class=\"wp-element-caption\">Sir Ababol II &#8211; Men\u00fc<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Sir Ababol 2<\/strong><br>\n<strong>Autor:<\/strong> Mojon Twins<br>\n<strong>Jahr:<\/strong> 2014<br>\n<strong>Download:<\/strong> <a href=\"http:\/\/www.mojontwins.com\/juegos_mojonos\/sir-ababol-2\/\" target=\"_blank\">Homepage<\/a><br>\n<strong>Rechner:<\/strong> Sinclair ZX Spectrum 48k\/128k<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>History<\/strong><br>\nSir Ababol hat sich in dem Land Belchite niedergelassen und verbringt seine Tage mit dem Anbau von Borretsch. Eines Tages wird er Zeuge von eindeutigen Zeichen am Himmel. Drei Kr\u00e4hen schweben \u00fcber seinem Kopf und ziehen konzentrische Kreise &#8211; dann erinnerte er sich an die weisen Wort des alten weisen Manns: &#8222;Wenn die Kr\u00e4hen niedrig fliegen wirst du G\u00e4nsehaut bekommen!&#8220;. Nat\u00fcrlich! Deswegen war seine Nase voll mit Rotz. Sie fror buchst\u00e4blich ein. Die Kr\u00e4hen waren tats\u00e4chlich Boten!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie kamen aus den L\u00e4ndern Freezias, eine Provinz von Badajoz. Ausgesandt von K\u00f6nig Yoghourteric, waren sie der verzweifelte Versuch Sir Ababol um Hilfe zu bitten. Also ging er nach Hause, packte seine Sachen und sprang auf sein Pferd, Anastatsio, auch wenn er nicht die geringste Idee hatte was wirklich passiert war. Auf seinem Weg legte er einen Stopp in Medinaceli ein f\u00fcr eine Tasse Chicoree-Latte und pr\u00fcfte kurz Minstrelbook, das mittelalterliche soziale Netzwerk, wo er die News \u00fcber acht junge Prinzen und Prinzessinnen h\u00f6rte, die in sechs T\u00fcrmen in Fridgeland gefangen gehalten wurden.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Nach drei Tagen Ritt durch Badajoz, kam er beim Eingang zu den W\u00e4ldern an wo die Herrscherin ihm erz\u00e4hlte was wirklich geschah: der teuflische Alchemisten-Druide Alastor de la Babucha, der Baron von Freezia und Marquis von Fridgeland hatte K\u00f6nig Yoghourteric zu einem &#8222;Ga\u00f1ote&#8220; Spiel herausgefordert &#8211; daf\u00fcr muss man so viel Wissen wie in das Gehirn passt, reinstopfen. Um das zu erreichen hat er ein Ger\u00e4t erfunden um das Wissen aus dem &#8222;Saft&#8220; von Prinzen zu extrahieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Extraktion verwandelt jeden jungen Prinzen in Freezia und Fridgeland in h\u00e4\u00dfliche Flederm\u00e4use. Als er sie sah konnte Sir Ababol nur noch rufen &#8222;Igitt, Luft-Ratten!&#8220;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/04\/Sir-Abadol-II-Ladescreen.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"381\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/04\/Sir-Abadol-II-Ladescreen.jpg\" alt=\"Sir Abadol II - Ladescreen\" class=\"wp-image-10504\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/04\/Sir-Abadol-II-Ladescreen.jpg 500w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/04\/Sir-Abadol-II-Ladescreen-300x229.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption class=\"wp-element-caption\">Sir Abadol II &#8211; Ladescreen<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Das Spiel<\/strong><br>\nKontrolliere Sir Ababol beim erklimmen der sechs T\u00fcrme von Freezia und bek\u00e4mpfe die in Flederm\u00e4use verwandelten Prinzen und Prinzessinnen, so dass du endlich den teuflischen Alastor zerst\u00f6ren kannst. Sir Ababol kann laufen und springen aber auch sein Schwert benutzen, das in alle Richtungen schlagen kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn sie mit dem Schwert getroffen werden, frieren die B\u00f6sewichte ein und Eis- oder Glasbl\u00f6cke splittern. Einige Eisbl\u00f6cke k\u00f6nnen M\u00fcnzen oder Extraleben enthalten, so dass es eine gute Idee ist, so viel wie m\u00f6glich zu zerbrechen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auf der Spitze jedes Turms wirst du einer oder zwei Flederm\u00e4usen gegen\u00fcber stehen. Um sie zu besiegen und sie wieder in Prinzen oder Prinzessinnen zu verwandeln, musst du sie dreimal mit deinem Schwert treffen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach jedem Turm kannst du den Shop besuchen und ein Kennwort oder Extra Leben kaufen.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/04\/Sir-Abadol-II-Screen.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"378\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/04\/Sir-Abadol-II-Screen.jpg\" alt=\"Sir Abadol II - Screen\" class=\"wp-image-10503\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/04\/Sir-Abadol-II-Screen.jpg 500w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/04\/Sir-Abadol-II-Screen-300x227.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption class=\"wp-element-caption\">Sir Ababol II &#8211; Screen<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Steuerung<\/strong><br>\nSinclair\/Kempston-Joystick, Tastatur<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tastaturbelegung<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">a &#8211; links bewegen<br>\nd &#8211; rechts bewegen<br>\ns &#8211; unten &#8211; Objekte benutzen, untersuchen, reden, Box nehmen, Box abgeben<br>\nn &#8211; oben &#8211; springen<br>\nm &#8211; Feuer &#8211; mit Schwert zuschlagen<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Conclusion<\/strong><br>\nSir Ababol II &#8211; The Ice Palace ist wieder ein Spiel von den Mojon Twins selbst &#8211;&nbsp;im Download der auf der Hompage zu finden ist, gibt es die 48K und die 128K Version. Das ist wieder ein Beispiel wie man die La Chuerra am besten einsetzt. Dazu noch eine &#8211; wie \u00fcblich &#8211; komplett irrwitzige Story. Wer die M\u00f6glichkeit hat, sollte unbedingt die 128K Version spielen, da hier im Hintergrund ein Klasse AY-Soundtrack l\u00e4uft.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/Ulky75zbmhI?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=en-GB&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>Sir Ababol 2 Autor: Mojon Twins Jahr: 2014 Download: Homepage Rechner: Sinclair ZX Spectrum 48k\/128k Geschichte Sir Ababol hat sich in dem Land Belchite niedergelassen \u2026<\/p>","protected":false},"author":2,"featured_media":10502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[102],"tags":[348,298,2400,666,977,96],"class_list":["post-8729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zx-spectrum","tag-la-chuerra","tag-mojon-twins","tag-review","tag-sinclair","tag-sir-ababol-ii","tag-spiele"],"wp-worthy-pixel":{"ignored":false,"public":"dc059fa6388e4a6d8b9f4b13e1d9f224","server":"","url":"https:\/\/vg06.met.vgwort.de\/na\/dc059fa6388e4a6d8b9f4b13e1d9f224"},"wp-worthy-type":"normal","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/04\/Sir-Abadol-II-Men\u00fc.jpg","_links":{"self":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/8729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/comments?post=8729"}],"version-history":[{"count":1,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/8729\/revisions"}],"predecessor-version":[{"id":44357,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/8729\/revisions\/44357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media\/10502"}],"wp:attachment":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media?parent=8729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/categories?post=8729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/tags?post=8729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}