{"id":8135,"date":"2015-03-02T18:00:03","date_gmt":"2015-03-02T17:00:03","guid":{"rendered":"http:\/\/www.jungsi.de\/?p=8135"},"modified":"2026-07-22T15:16:29","modified_gmt":"2026-07-22T13:16:29","slug":"leovigildo-retro-sinclair-zx-spectrum","status":"publish","type":"post","link":"https:\/\/www.jungsi.de\/en\/leovigildo-retro-sinclair-zx-spectrum\/","title":{"rendered":"Leovigildo [Sinclair ZX Spectrum]"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Leovigildo<\/strong><br><strong>Autor:<\/strong> Mojon Twins<br><strong>Jahr:<\/strong> 2014<br><strong>Rechner:<\/strong> Sinclair ZX Spectrum<br><strong>Download:<\/strong> <a href=\"http:\/\/www.mojontwins.com\/juegos_mojonos\/leovigildo-pero-que-haces-leovigildo-leovigildo\/\" target=\"_blank\">Homepage<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Puzzle-Abenteuer\/Action-Puzzle\/Action-Abenteuer Spiel f\u00fcr den ZX Spectrum 48K in drei getrennten Dateien (plus eine extra Datei f\u00fcr das Spielende!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>History<\/strong><br><em>Kapitel 1: \u201cTHE CONSPIRACY\u201d<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das war sicher nicht der beste Moment von Duke&nbsp;Benoit Rundown, Erbe des gro\u00dfen Haus von&nbsp;Salvalamalvadetierra. &nbsp;Unf\u00e4hig seine unb\u00e4ndige Vorliebe f\u00fcr Wassermelonen Erdn\u00fcsse zu kontrollieren verschwendete er das Verm\u00f6gen&nbsp;der&nbsp;Salvalamalvadetierras, das diese seit Jahrhunderten gesammelt hatten, seid sein Ahne &#8211; Victor Alberto Saavedra, den legend\u00e4ren Schatz des afrikanischen Stammes der Jamacucos (Provinz Badajoz) entdeckt hatte und alles in eine Schiffahrtsgesellschaft, eine Bergbau Gesellschaft und eine Partnervermittelung investiert hat.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Die Bauf\u00e4lligkeit war so gro\u00df, das fast alle Kunstwerke und Wertgegenst\u00e4nde aus seinem riesigen Anwesen langsam verschwanden und nur ein paar Spinnweben blieben. Auf die eine oder andere Weise musste er auch seine 101 Bediensteten vertreiben. Die H\u00e4lfte verlie\u00df das Anwesen mit frischem Wind, w\u00e4hrend die anderen herumschwirren und ihr Abfindung fordern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der einzige der&nbsp;loyal zum Duke blieb, war Loeovigildo, sein Butler. Er wurde als Butler geboren, wie vor ihm sein Vater, und davor seines Vaters Vater Butler f\u00fcr die&nbsp;Salvalamalvadetierra gewesen waren&#8230;der arme Diener kannte kein anderes Leben und daher begehrte er nichts anderes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Herzogin, die wunderbare Lady&nbsp;Marie Antoinette hatte genug von ihrem Ehemann und konnte es nicht ausstehen das er das gesamt Familienverm\u00f6gen verschleuderte, so dass sie sich entschied, sich darum zu k\u00fcmmern und begann zu intrigieren. Der einzige Besitz, der zu diesem Zeitpunkt \u00fcbrig war, war das Anwesen selbst. Da der Duke war so ungeschickt und bewahrte die Besitzurkunde in seinem kleinen B\u00fcro auf, verga\u00df aber sie zu unterschreiben. Die Herzogin musste nur die Papiere an sich nehmen, unterschreiben und konnte den Duke rauswerfen und zuletzt das Anwesen behalten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da sie eine Frau von hohem Stand war, entschied sie sich den armen Leovigildo auszusenden um f\u00fcr sie die schmutzige Arbeit zu erledigen. Nebenbei, um es noch schlimmer zu machen war der Butler total verliebt in die Herzogin. In der Vergangenheit war es Leovigildo einige Male m\u00f6glich sich in die privaten R\u00e4ume der Prinzessin zu stehlen (welcher durch das Bet\u00e4tigen eines mysteri\u00f6sen Artefakts welches sich in der Ankleider in ihrem Schlafzimmer befand zu \u00f6ffnen war). Er wu\u00dfte das sie dort aus unerfindlichen Gr\u00fcnden eine Flasche mit Chloroform aufbewahrte. Mehr als einmal tr\u00e4umte er davon, die Herzogin mit diesem Chloroform zu bet\u00e4uben, sie zu entf\u00fchren und in den Wald zu bringen um&nbsp;ihr seine gro\u00dfe Liebe zu demonstrieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Rolle von Leovigildo, musst du dich entscheiden was du willst..Wirst du deinen Plan mit der Entf\u00fchrung der Herzogin umsetzen? Oder wirst du dem Plan der Herzogin folgen, die Besitzurkunde f\u00fcr das Anwesen zu stehlen? Wirst du beides tun? Nichts von dem? Du kannst entscheiden!<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/03\/Leovigildo-Screen-Chapter-1.gif\"><img loading=\"lazy\" decoding=\"async\" width=\"256\" height=\"192\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/03\/Leovigildo-Screen-Chapter-1.gif\" alt=\"Leovigildo - Screen - Chapter 1\" class=\"wp-image-9598\"\/><\/a><figcaption class=\"wp-element-caption\">Leovigildo &#8211; Screen &#8211; Chapter 1<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><em>Kapitel 2: \u201cTHE FLIGHT\u201d<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Am Ende entscheidet sich Leovigildo daf\u00fcr beides zu machen: du hast f\u00fcr die Herzogin die Besitzurkunde, hast ihr aber auch die Flasche Chloroform gestohlen. Die Herzogin war unglaublich froh, als sie aber die Sache mit dem Chloroform entdeckte (Leovigildo war ein dummer Junge!) verliebte sie sich ganz verzweifelt in den Butler &#8211; aus unerfindlichen Gr\u00fcnden. Herzoginnen &#8222;Angelegenheiten&#8220;. Dieser pl\u00f6tzliche Anfall von Liebe tr\u00fcbte ihr Urteil und sie konnte sich nicht zur\u00fcckhalten und warf sich in die Arme ihres neuen Geliebten. Der Herzog, von der wilden Liebelei alarmiert, brach in die privaten R\u00e4ume der Herzogin ein und erwischte sie auf frischer Tat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Herzogin und Leovigildo, die ihre kostbare Besitzurkunde hatten, sprangen durch ein kleines Fenster und verschwanden im Wald. Obwohl es im dichten Wald viele K\u00e4fer gab, schien die Herzogin ziemlich sicher, dass sie ihn durchqueren wollte. Sie schien etwas obskures vor zu haben, als wenn sie einen Plan im \u00c4rmel versteckt h\u00e4tte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leovigildo, wird &#8211; ganz wie ein Champion den Weg bereiten &#8211; Kisten werfen!<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/03\/Leovigildo-Screen-Chapter-2.gif\"><img loading=\"lazy\" decoding=\"async\" width=\"256\" height=\"192\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/03\/Leovigildo-Screen-Chapter-2.gif\" alt=\"Leovigildo - Screen - Chapter 2\" class=\"wp-image-9597\"\/><\/a><figcaption class=\"wp-element-caption\">Leovigildo &#8211; Screen &#8211; Chapter 2<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><em>Kapitel 3: \u201cTHE CIRCUS\u201d<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach dem Durchqueren des Waldes, gelangten Leovigildo und die Herzogin auf dem freien Platz des Europ\u00e4ischen Zirkus. Dort er\u00f6ffnete Marie Antoinette dem Butler ihre wahren Pl\u00e4ne: Sie hatte immer davon getr\u00e4umt das Universum zu beherrschen und eine teuflische Herrscherin zu werden!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leovigildo war etwas \u00fcberrascht als er die Herzogin in das Zirkuszelt kriechen sah. Er versuchte sie zu stoppen, da ihm die legend\u00e4re &#8222;Wut der Zirkusleute&#8220; bekannt war. Sie ri\u00df sich aber los und sagte das es sehr wichtig sei in die Kabine des Zirkus zu gelangen, da dies der Raum ist, von dem der Zirkus kontrolliert wird. Dies ist der erste Schritt die Welt zu beherrschen &#8211; jeder wei\u00df das!!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcberrascht, aber sehr verliebt, beschlo\u00df Leovigildo ihr zu folgen. &#8222;Dieses Mal werde ich mich um mich selbst k\u00fcmmern.&#8220; sagte die Herzogin. &#8222;Als ich j\u00fcnger war, arbeitete ich in einem Zirkus und wu\u00dfte mich in dieser Umgebung zu bewegen. In meinen j\u00fcngeren Jahren war ich als Lady&nbsp;Poto\u00f1a bekannt und war sehr ber\u00fchmt. Das war als mich der Duke entdeckte. Ich verliebte mich in seine Augen, seine Versprechungen von Liebe und die Akkorde seiner Balalaika&#8230;.ich war jung und ungest\u00fcm. Und sieh mich nun an&#8230;.&#8220;. Dann pausierte sie dramatisch und sah dem Horizont entgegen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8222;Ich werde den F\u00fchrerraum dieses Zirkus so sicher finden, wie ich&nbsp;Marie Antoinette Salvalamalvadetierra hei\u00dfe!&#8220;, rief sie und verschwand unter dem Vordach.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/03\/Leovigildo-Screen-Chapter-3.gif\"><img loading=\"lazy\" decoding=\"async\" width=\"256\" height=\"192\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/03\/Leovigildo-Screen-Chapter-3.gif\" alt=\"Leovigildo - Screen - Chapter 3\" class=\"wp-image-9596\"\/><\/a><figcaption class=\"wp-element-caption\">Leovigildo &#8211; Screen &#8211; Chapter 3<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Spielweise\/Steuerung<\/strong><br>Das Spiel ist in drei unterschiedliche Bl\u00f6cke unterteilt, einer pro Kapital, die sich unabh\u00e4ngig voneinander laden und spielen lassen. Es gibt einen vierten, letzten Block mit der Endsequenz. Daf\u00fcr ben\u00f6tigst du ein Kennwort, das am Ende des dritten Kapitels vergeben wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Steuerung ist in jedem Kapitel \u00e4hnlich, auch wenn die Spielweise unterschiedlich ist. Du kannst Kisten nehmen und tragen durch Dr\u00fccken von &#8222;UNTEN&#8220;, und sie woanders fallen lassen indem du nochmal &#8222;UNTEN&#8220; dr\u00fcckst. Im zweiten Kapitel kannst du mit den Kisten auch Feinde t\u00f6ten indem du &#8222;FEUER&#8220; dr\u00fcckst. &nbsp;Im dritten Kapitel funktionieren die Kisten auch als Trampolin und k\u00f6nnen auch getragen werden, sind aber so schwer, das sie deine Energie aufzehren. In jedem Kapitel kann &#8222;UNTEN&#8220; verwendet werden um ein Objekt zu nehmen, zu untersuchen, damit zu sprechen oder es zu benutzen. Du kannst dein Inventar mit &#8222;Z&#8220; verwalten und mit dem Cursor den aktiven Slot mit dem Objekt das du benutzen willst ausw\u00e4hlen bzw. den Slot in dem du ein neues Objekt ablegen willst.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Du kannst zwei verschiedene Tastatureinstellungen verwenden&nbsp;(WSADNM, QAOPM) und Sinclair-\/Kempston Joystick. &nbsp;Hier sind die Einstellungen &#8211; zuerst f\u00fcr die&nbsp;WSADNM Konfiguration, die OPQAM Konfiguration und dann f\u00fcr die&nbsp;Joysticks.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A, O, Links:\u00a0geh nach links<br>D, P, Rechts: geh nach rechts<br>S, A, Unten: benutze\u00a0, untersuche, sprich (mit) Objekt\u00a0, nimm Box, leg Box ab.<br>N, Q, Oben: springen<br>M, Feuer: Wirf Box\u00a0(Kapitel 2)<br>Z:\u00a0w\u00e4hle Platz im Inventar<br>H: Pause<br>Y: zur\u00fcck zum Start<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das erste Kapitel hat vier verschiedene Enden, abh\u00e4ngig von den Aufgaben die du abschlie\u00dft, bevor du mit der Herzogin sprichst. Nur eines dieser Enden ist das &#8222;Richtige&#8220; (entsprechend der Geschichte)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im zweiten Kapitel musst du alle Feinde auf einem Bildschirm t\u00f6ten, bevor du zum n\u00e4chsten kannst. Sollten dir die Kisten ausgehen, kannst du den Level neu starten indem du auf das spezielle Teil gehst und &#8222;UNTEN&#8220; dr\u00fcckst &#8211; du verlierst aber ein Leben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im dritten Kapitel, steuerst du die Herzogin, die auf Trampolin-Kisten springen kann um h\u00f6her zu kommen. Du kannst diese Kisten auch transportieren, diese sind aber so schwer, das du Energie verlierst.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Map: <a href=\"http:\/\/maps.speccy.cz\/map.php?id=Leovigildo\" target=\"_blank\">Leovigildo! &#8211; The Map<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Conclusion<\/strong><br>Was soll man da noch sagen &#8211; die MojonTwins pers\u00f6nlich haben zugeschlagen. Ein hervorragendes Spiel in drei Kapitel, das auch f\u00fcr 30 Jahren f\u00fcr Furore gesorgt h\u00e4tte. Ich hoffe das es gen\u00fcgend gibt und das Spiel bis zum Ende spielen &#8211; das ist das sch\u00f6nste f\u00fcr die Entwickler. Was f\u00fcr ein Aufwand! \ud83d\ude42<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/FxG90Au0CX4?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=en-GB&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>LeovigildoAutor: Mojon TwinsJahr: 2014Rechner: Sinclair ZX SpectrumDownload: Homepage Ein Puzzle-Abenteuer\/Action-Puzzle\/Action-Abenteuer Spiel f\u00fcr den ZX Spectrum 48K in drei getrennten Dateien (plus eine extra Datei f\u00fcr \u2026<\/p>","protected":false},"author":2,"featured_media":9595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[102],"tags":[2400,666,96],"class_list":["post-8135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zx-spectrum","tag-review","tag-sinclair","tag-spiele"],"wp-worthy-pixel":{"ignored":false,"public":"ec48a4b5236e4a1d9e469062e2b0358b","server":"","url":"https:\/\/vg07.met.vgwort.de\/na\/ec48a4b5236e4a1d9e469062e2b0358b"},"wp-worthy-type":"normal","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2015\/03\/Leovigildo-Ladescreen.gif","_links":{"self":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/8135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/comments?post=8135"}],"version-history":[{"count":1,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/8135\/revisions"}],"predecessor-version":[{"id":43782,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/8135\/revisions\/43782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media\/9595"}],"wp:attachment":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media?parent=8135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/categories?post=8135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/tags?post=8135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}