{"id":6059,"date":"2014-05-18T12:36:41","date_gmt":"2014-05-18T11:36:41","guid":{"rendered":"http:\/\/www.jungsi.de\/?p=6059"},"modified":"2026-08-27T16:25:46","modified_gmt":"2026-08-27T14:25:46","slug":"retro-sinclair-zx-spectrum-spielvorstellung-terrorlandia","status":"publish","type":"post","link":"https:\/\/www.jungsi.de\/en\/retro-sinclair-zx-spectrum-spielvorstellung-terrorlandia\/","title":{"rendered":"Terrorlandia [Sinclair ZX Spectrum]"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Terrorlandia<\/strong><br><strong>Jahr:<\/strong> 2014<br><strong>Autor:<\/strong> Favio Didone<br><strong>Rechner:<\/strong> Sinclair ZX Spectrum 48K<\/p>\n\n\n    <a href=\"https:\/\/www.jungsi.de\/en\/?dl=terrorlandia-1-8928\" class=\"dl-box\">\n        <span class=\"dl-box__icon\" aria-hidden=\"true\">\u2b07<\/span>\n        <span class=\"dl-box__info\">\n            <span class=\"dl-box__label\">Terrorlandia<\/span>\n                            <span class=\"dl-box__meta\">18,19 KB<\/span>\n                    <\/span>\n        <span class=\"dl-box__count\">147\u00d7<\/span>\n    <\/a>\n    \n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die \u00dcbersetzung zu diesem Spiel k\u00f6nnte sich etwas &#8222;holprig&#8220; anh\u00f6ren, da es nur eine spanische Anleitung gibt und das nicht ganz so einfach war. \ud83d\ude42 Das Spiel wurde wieder mit der <strong>La Chuerra Engine<\/strong> der <strong>Mojon Twins<\/strong> erstellt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>History<\/strong><br>Gruselige und erschreckende Geschichten aus dem fernen Reich Terrorlandia. Skelette durchstreifen in der Nacht die dunklen G\u00e4nge des Schlosses. Vampire streunen durch die Finternis und s\u00e4en Besorgnis zwischen den Bewohnern der Zitadelle. Um diese Schreckensherrschaft zu beenden, findet sich unser Held selbst in der schwierigen Aufgabe, alle Mystischen Kreuze zu sammeln und zu zerst\u00f6ren (insgesamt 25 sind in der gesamten Burg verstreut), da sie die Quelle der Gr\u00e4uel seiner Bewohner sind. Um dieses Ziel zu erreichen, muss er triumphieren.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Steuerung<\/strong><br>Am unteren Bildschirmrand sind vier Symbole &#8211; hier die Bedeutungen von rechts nach links:<br>&#8211; Zauberkessel: Anzahl der gesammelten Zauberkessel &#8211; um die Hexen welche&nbsp;die Durchg\u00e4nge blockieren zu &#8222;beseitigen&#8220; muss man die auf dem Weg liegenden Zauberkessel sammeln &#8211; f\u00fcr jede Hexe ben\u00f6tigt man einen Kessel<br>&#8211; Lebenspunkte des Helden: ber\u00fchrt er Gegner oder f\u00e4llt er in Gruben verliert er Lebenspunkte &#8211; logisch: sind diese auf Null ist das Spiel zu Ende<br>&#8211; Mystische Kreuze: Anzahl der gesammelten Mystischen Kreuze<br>&#8211; Graf Macrobia: Wenn auf sie drauf springt werden sie aus dem Spiel entfernt &#8211; die Zahl zeigt nur an wieviele man schon beseitigt hat<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"389\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2014\/05\/Terrorlandia-Men\u00fc.jpg\" alt=\"Terrorlandia - Men\u00fc\" class=\"wp-image-6065\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2014\/05\/Terrorlandia-Men\u00fc.jpg 500w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2014\/05\/Terrorlandia-Men\u00fc-300x233.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><figcaption class=\"wp-element-caption\">Terrorlandia &#8211; Men\u00fc<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><em>Feinde<\/em><br>Flederm\u00e4use: ziehen bei Ber\u00fchrung Leben ab<br>Skelette: ziehen bei Ber\u00fchrung Leben ab<br>Graf Macrobia: zieht auch Leben ab, kann aber durch einen Sprung beseitigt werden<br><em>Andere Objekte<\/em><br>&#8211; Plattformen: dienen dazu um an h\u00f6her gelegene Stellen zu gelangen<br>&#8211; Hexen: blockieren Durchg\u00e4nge und k\u00f6nnen mit Zauberkessel&nbsp;&#8222;bestochen&#8220; werden<br>&#8211; Spie\u00dfe: ziehen bei Ber\u00fchrung Leben ab<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>o: links<\/li>\n\n\n\n<li>p: rechts<\/li>\n\n\n\n<li>Space: springen<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Sinclair und Kempston Joystick<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"393\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2014\/05\/Terrorlandia-Screen.jpg\" alt=\"Terrorlandia Screen\" class=\"wp-image-6063\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2014\/05\/Terrorlandia-Screen.jpg 500w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2014\/05\/Terrorlandia-Screen-300x236.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><figcaption class=\"wp-element-caption\">Terrorlandia &#8211; Screen<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Map: http:\/\/maps.speccy.cz\/map.php?id=Terrorlandia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Conclusion<\/strong><br>Ein nettes aber sehr kurzes Spiel \ud83d\ude42 Man muss sich vorstellen, dass ich Terrolandia im zweiten Test bei dem ich auch das Video machte schon durchgespielt habe. Das ist etwas ungew\u00f6hnlich &#8211; evt. ist es auch zu einfach. Mir kam hier nat\u00fcrlich entgegen, dass man bei Ber\u00fchrung nicht direkt ein Leben abgezogen bekommt, sondern Hitpoints. Die Grafiken sind nett gemacht &#8211; es gibt den einen oder anderen Bug &#8211; der aber nicht st\u00f6rt &#8211; die Spielzeit betr\u00e4gt ca. 15 Minuten \ud83d\ude42<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/c3i4aMHxPJg?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=en-GB&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>TerrorlandiaJahr: 2014Autor: Favio DidoneRechner: Sinclair ZX Spectrum 48K Die \u00dcbersetzung zu diesem Spiel k\u00f6nnte sich etwas &#8222;holprig&#8220; anh\u00f6ren, da es nur eine spanische Anleitung gibt \u2026<\/p>","protected":false},"author":2,"featured_media":6064,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[102],"tags":[2400,666,96],"class_list":["post-6059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zx-spectrum","tag-review","tag-sinclair","tag-spiele"],"wp-worthy-pixel":{"ignored":false,"public":"2082de87dd1948a290078a282f412775","server":"","url":"https:\/\/vg09.met.vgwort.de\/na\/2082de87dd1948a290078a282f412775"},"wp-worthy-type":"normal","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2014\/05\/Terrorlandia-Ladescreen.jpg","_links":{"self":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/6059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/comments?post=6059"}],"version-history":[{"count":3,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/6059\/revisions"}],"predecessor-version":[{"id":44628,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/6059\/revisions\/44628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media\/6064"}],"wp:attachment":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media?parent=6059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/categories?post=6059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/tags?post=6059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}