{"id":4016,"date":"2013-11-12T17:26:15","date_gmt":"2013-11-12T16:26:15","guid":{"rendered":"http:\/\/www.jungsi.de\/?p=4016"},"modified":"2026-08-25T14:44:27","modified_gmt":"2026-08-25T12:44:27","slug":"retro-sinclair-zx-spectrum-spieletest-gem-chaser-2","status":"publish","type":"post","link":"https:\/\/www.jungsi.de\/en\/retro-sinclair-zx-spectrum-spieletest-gem-chaser-2\/","title":{"rendered":"Gem Chaser 2 [Sinclair ZX Spectrum]"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Gem Chaser 2<\/strong><br><strong>Jahr:<\/strong> 2013<br><strong>Autor:<\/strong> BobS<br><strong>Rechner:<\/strong> ZX Spectrum 48\/128K<br><a href=\"https:\/\/bobs-stuff.itch.io\/gem-chaser-2\" target=\"_blank\" rel=\"noreferrer noopener\">Downloads<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Spiel <strong>Gem Chaser 2<\/strong> ist die Fortsetzung von <strong><a href=\"https:\/\/bobs-stuff.itch.io\/gem-chaser\" target=\"_blank\" rel=\"noreferrer noopener\">Gem Chaser<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Spielweise<\/strong><br>Sammle einfach die farbigen Steine, die Deiner eigenen Farbe entsprechen &#8211; wechsle dann Deine Farbe um die anderen zu sammeln &#8211; einfach &#8211; aber \u00fcberraschend herausfordernd bei 70 Level die bew\u00e4ltigt werden sollen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hinweise<\/strong><br>Nicht einfache nur mehr Level, sondern eine Fortsetzung mit komplett neuen Level, Spielemechaniken und Level-Struktur &#8211; also eine Evolution. Neue Mechaniken beinhalten Gravity-Flips, horizontale T\u00fcren und Portal um einige neue hinterh\u00e4ltige Level zu machen.<br>Belohnungen gibt es nun f\u00fcr die Geschwindigkeit in der jedes Level gemeistert wird. Ebenso das die Farbe beim Sammeln der Steine immer stimmt und f\u00fcr das Finden des Secret Star&#8217;s eines Level. Das alles kann in einem einzigen Spiel erreicht werden oder \u00fcber mehrere Sitzungen hinweg was den Fortschritt im Spiel eine offenere Angelegenheit macht. Der Kommentar der Retro Gamer beim Originalspiel, das es nicht m\u00f6glich ist den Fortschritt zwischen zwei Sitzungen zu speichern, wurde ernst genommen und eine M\u00f6glichkeit eingebaut um den Fortschritt auf Band zu sichern und wieder herzustellen.<\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/10\/GemChaser-2-Ladescreen.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"385\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/10\/GemChaser-2-Ladescreen.jpg\" alt=\"GemChaser 2 - Ladescreen\" class=\"wp-image-4278\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/10\/GemChaser-2-Ladescreen.jpg 500w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/10\/GemChaser-2-Ladescreen-300x231.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption class=\"wp-element-caption\">GemChaser 2 &#8211; Ladescreen<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Einfach alle Steine eines Levels sammeln &#8211; unabh\u00e4ngig von der richtigen Farbe &#8211; entsperrt die n\u00e4chsten 5 Level danach. Um das Spiel aber komplett zu spielen m\u00fcssen von jedem Level alle drei Auszeichnungen erreicht werden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Colour Matcher &#8211; Alle Steine wurden mit der richtigen Farbe gesammelt<\/li>\n\n\n\n<li>Fast Mover &#8211; Alle Steine wurden innerhalb der Zeit gesammelt<\/li>\n\n\n\n<li>Star Catcher &#8211; Ein Stern der in jedem Level versteckt ist und eine bestimmte Farbe hat muss gesammelt werden. Er kannann nur gesehen und gesammelt werden wenn der Spieler die passenden Farbe hat.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Eine f\u00fcnf Sekunden Zeitstrafe wird f\u00fcr jeden Stein vergeben, der gesammelt wird wenn man nicht die passende Farbe hat.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/10\/GemChaser-2-Men\u00fc.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"368\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/10\/GemChaser-2-Men\u00fc.jpg\" alt=\"Gem Chaser 2 - Men\u00fc\" class=\"wp-image-4275\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/10\/GemChaser-2-Men\u00fc.jpg 500w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/10\/GemChaser-2-Men\u00fc-300x221.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption class=\"wp-element-caption\">Gem Chaser 2 &#8211; Men\u00fc<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Steuerung<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tastatur:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>z &#8211; links<\/li>\n\n\n\n<li>x &#8211; rechts<\/li>\n\n\n\n<li>l &#8211; springen<\/li>\n\n\n\n<li>b &#8211; zur\u00fcck (zeigt das Spielmen\u00fc oder springt zum vorherigen Men\u00fc zur\u00fcck)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Alle Tasten k\u00f6nnen anders definiert werden<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Joystick:<br>Das Spiel kann voll mit einem Kempston, Protek\/Cursor oder Sinclair Interface Joystick kontrolliert werden.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/10\/GemChaser2-Level-6.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"384\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/10\/GemChaser2-Level-6.jpg\" alt=\"Gem Chaser 2 - Level 6\" class=\"wp-image-4276\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/10\/GemChaser2-Level-6.jpg 500w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/10\/GemChaser2-Level-6-300x230.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption class=\"wp-element-caption\">Gem Chaser 2 &#8211; Level 6<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Conclusion<\/strong><br>Wieder ein sehr sch\u00f6nes Spiel von BobS und eine sehr gelungene Fortsetzung vom ersten Teil mit vielen Verbesserungen im Detail. Sehr sch\u00f6n ist die L\u00f6sung mit den zu erreichenden Herausforderungen und der M\u00f6glichkeit zu speichern. Trotzdem bleibt es f\u00fcr mich oft schwierig zu Zeitvorgaben zu erreichen. Aber hier bin ich ja nicht der Ma\u00dfstab \ud83d\ude42 Sehr gelungen!<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/dCq4aJqJccA\" width=\"420\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Gem Chaser 2Jahr: 2013Autor: BobSRechner: ZX Spectrum 48\/128KDownloads Das Spiel Gem Chaser 2 ist die Fortsetzung von Gem Chaser. SpielweiseSammle einfach die farbigen Steine, die \u2026<\/p>","protected":false},"author":2,"featured_media":4275,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[102],"tags":[2400,666,96],"class_list":["post-4016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zx-spectrum","tag-review","tag-sinclair","tag-spiele"],"wp-worthy-pixel":{"ignored":false,"public":"8f161de2898246f4a2f277bee3c4e40a","server":"","url":"https:\/\/vg03.met.vgwort.de\/na\/8f161de2898246f4a2f277bee3c4e40a"},"wp-worthy-type":"normal","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/10\/GemChaser-2-Men\u00fc.jpg","_links":{"self":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/4016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/comments?post=4016"}],"version-history":[{"count":2,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/4016\/revisions"}],"predecessor-version":[{"id":44456,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/4016\/revisions\/44456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media\/4275"}],"wp:attachment":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media?parent=4016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/categories?post=4016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/tags?post=4016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}