{"id":2967,"date":"2013-03-24T17:15:15","date_gmt":"2013-03-24T16:15:15","guid":{"rendered":"http:\/\/www.jungsi.de\/?p=2967"},"modified":"2026-08-27T22:02:32","modified_gmt":"2026-08-27T20:02:32","slug":"retro-commodore-c64sd-v2-0-infinity","status":"publish","type":"post","link":"https:\/\/www.jungsi.de\/en\/retro-commodore-c64sd-v2-0-infinity\/","title":{"rendered":"C64SD V2.0 Infinity [Commodore 64]"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Die erste Erweiterung f\u00fcr den C64 ist angekommen: ein SD-Kartenleser! Ich besitze bereits \u00e4hnliche Ger\u00e4te f\u00fcr Sinclair und Atari Computer. Beim C64 emuliert dieser haupts\u00e4chlich ein Diskettenlaufwerk (1541). Nach einiger Recherche und da ich nicht selbst l\u00f6ten wollte, entschied ich mich f\u00fcr die C64SD V2.0 Infinity von Manosoft aus Italien. Das Ger\u00e4t kommt in einem ansprechenden Geh\u00e4use, und sowohl der Kassetten- als auch der Floppyanschluss sind durchgeschleift, sodass problemlos weitere Ger\u00e4te angeschlossen werden k\u00f6nnen. Die mitgelieferte Bedienungsanleitung in Englisch und Italienisch ist f\u00fcr den Einstieg v\u00f6llig ausreichend. Auf der Manosoft-Website kann ein Image heruntergeladen werden, das man einfach auf eine SD-Karte kopiert, einlegt und sofort startet.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Nicht alle meine SD-Karten wurden erkannt \u2013 jedoch funktionierte eine alte 1GB-Karte aus einer Digitalkamera..<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Unterschied zu den Sinclair (divIDE) und Atari (GigaFile) Ger\u00e4ten f\u00fchrt dieses Ger\u00e4t nicht zu einer Beschleunigung der Ladezeiten. Sie sind genauso schnell bzw. langsam wie beim Einsatz einer Diskette. \ud83d\ude09<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DIP-Switch f\u00fcr die Einstellung der Ger\u00e4te-Nummer (Leider in der Anleitung nicht beschrieben und am Ger\u00e4t nicht erkennbar) &#8211; bei Auslieferung ist es als Ger\u00e4t 8 konfiguriert.<br>ID 8: Schalter 1: OFF &#8211; Schalter 2: OFF<br>ID 9: Schalter 1: ON &#8211; Schalter 2: OFF<br>ID 10: Schalter 1: OFF &#8211; Schalter 2: ON<br>ID 11: Schalter 1: ON &#8211; Schalter 2: ON<br>Damit kann man dem <strong>C64SD<\/strong> z.B. die Nummer 9 geben und kann direkt das Floppy-Laufwerk zus\u00e4tzlich anschlie\u00dfen und mit der Nummer 8 ansprechen.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-1.jpg\" alt=\"C64SD V2.0 INFINITY komplett\" class=\"wp-image-2992\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-1.jpg 450w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-1-225x300.jpg 225w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><figcaption class=\"wp-element-caption\">C64SD V2.0 INFINITY komplett<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Hier nun noch die \u00dcbersetzung der wichtigsten Teile der Anleitung die dem Ger\u00e4te beiliegen:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Warum dieses SD2IEC?<\/strong><\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>keine externe Stromversorgung n\u00f6tig<\/li>\n\n\n\n<li>es werden keine Verbindungskabel in den C64 ben\u00f6tigt<\/li>\n\n\n\n<li>es wird kein Floppykabel ben\u00f6tigt<\/li>\n\n\n\n<li>kompatibel mit anderen Commodore Systemen<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Technische Spezifikationen\/Neuigkeiten<\/strong><\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reset Knopf<\/li>\n\n\n\n<li>Disk Knopf &#8211; Disk Emu wechseln (oben ausw\u00e4hlen)<\/li>\n\n\n\n<li>Reverse Knopf (unten ausw\u00e4hlen oder f\u00fcr zuk\u00fcnftige Firmware)<\/li>\n\n\n\n<li>Dip-Schalter &#8211; Konfiguration von Ger\u00e4t 8,9,10,11<\/li>\n\n\n\n<li>LED gr\u00fcn &#8211; Strom<\/li>\n\n\n\n<li>LED rot &#8211; besch\u00e4ftigt<\/li>\n\n\n\n<li>LED blau &#8211; lesen\/schreiben<\/li>\n\n\n\n<li>durchgeschliffener Floppy-Anschluss (um die Anzahl der m\u00f6glichen Verbindungen zu erh\u00f6hen)<\/li>\n\n\n\n<li>Geh\u00e4use in Aluminium (Schutz und Sicherheit)<\/li>\n\n\n\n<li>ATMEGA 1284P (128K) &#8211; doppelte Kapazit\u00e4t gegen\u00fcber V2.0 Advanced<\/li>\n\n\n\n<li>durchgeschliffener Kassetten-Anschluss (mit Adapter)<\/li>\n\n\n\n<li>Reset User Port (mit Kabel Add-On)<\/li>\n\n\n\n<li>Upgrade Firmware FAT16\/FAT32<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-3.jpg\" alt=\"C64SD V2.0 INFINITY - Vorderseite\" class=\"wp-image-2994\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-3.jpg 450w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-3-225x300.jpg 225w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><figcaption class=\"wp-element-caption\">C64SD V2.0 INFINITY &#8211; Vorderseite<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Einf\u00fchrung<\/strong><\/em><br>Das C64SD ist so konzipiert, dass es einfach zu verwenden und kompakt ist. Es kann direkt an den C64\/C64C\/C64G und VIC20 angeschlossen werden, da diese Computer das gleiche Anschlusslayout aufweisen. Der Tape-Anschluss versorgt das Ger\u00e4t mit Strom, w\u00e4hrend der IEC-Anschluss die Kommunikation mit dem Floppy-Laufwerk erm\u00f6glicht.<br>Die INFINITY-Version des C64SD verf\u00fcgt \u00fcber durchgeschleifte Floppy- und Kassettenanschl\u00fcsse, was sie vielseitig macht. \u00dcber DIP-Switches konfigurierbar, k\u00f6nnen eine oder mehrere externe 1541-Laufwerke angeschlossen werden, entweder vor oder hinter dem Ger\u00e4t. Es ist auch m\u00f6glich, mehrere C64SD-Ger\u00e4te in Reihe zu schalten.<br>Um das C64SD mit anderen Commodore-Computern zu nutzen, kann der External-Power-Jumper entfernt werden, um das Ger\u00e4t mit einem externen 9V-Netzteil zu betreiben. So l\u00e4sst es sich auch mit dem C16, Plus4, C128 und anderen Modellen verwenden.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-2.jpg\" alt=\"C64SD V2.0 INFINITY - R\u00fcckseite\" class=\"wp-image-2993\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-2.jpg 450w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-2-225x300.jpg 225w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><figcaption class=\"wp-element-caption\">C64SD V2.0 INFINITY &#8211; R\u00fcckseite<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Funktionalit\u00e4t<\/strong><\/em><br>Das C64SD verwendet dieselbe Firmware wie das SD2IEC und ist daher aufr\u00fcstbar. Die Karte unterst\u00fctzt alle k\u00fcrzlich hinzugef\u00fcgten Funktionen sowie zuk\u00fcnftige Entwicklungen. Sie ist jedoch nicht vollst\u00e4ndig kompatibel mit Schnellladeprogrammen \u2013 es gibt immer noch M2i oder andere Versionen deiner bevorzugten Spiele.<br>F\u00fcr Informationen zur Firmware und Unterst\u00fctzung dazu:<br>http:\/\/www.C64-wiki.com\/index.php\/SD2IEC<br>Einige unterst\u00fctzte Formate:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>.PRG Spiele C64<\/li>\n\n\n\n<li>.P00 Cartridge Versionen<\/li>\n\n\n\n<li>.D64 Spiele Image Disk .D64<\/li>\n\n\n\n<li>.M2I Multiload Spiele<\/li>\n\n\n\n<li>.D71 D71 &#8211; doppelseitige 1571er Disk Images<\/li>\n\n\n\n<li>.D81 3,5&#8220; 1581er Disk Images<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-5.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-5.jpg\" alt=\"C64SD V2.0 INFINITY - Draufsicht\" class=\"wp-image-2996\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-5.jpg 500w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-5-300x225.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption class=\"wp-element-caption\">C64SD V2.0 INFINITY &#8211; Draufsicht<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Das System ist unkompliziert und z\u00fcgig. Auf der Webseite www.manosoft.it kannst du ein Paket herunterladen und es auf eine SD-Karte kopieren, die maximal 4\/8 GB gro\u00df sein darf und mit SDHC-Karten &#8211; FAT 12\/16\/32 &#8211; kompatibel ist.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>verbinde C64SD V2.0 INFINITY<\/li>\n\n\n\n<li>lege die SD-Karte ein<\/li>\n\n\n\n<li>schalte den C64 ein und w\u00e4hle:<\/li>\n<\/ul>\n\n\n\n<pre class=\"wp-block-preformatted\">LOAD\"$\",8 (lade das Verzeichnis der SD-Karte)\nLIST (zeige das Verzeichnis der SD-Karte an)<\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">Funktioniert wie ein richtiges Floppy-Laufwerk. Nun zu wichtigeren Dingen:<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">LOAD\"MENU\",8 (C64)<br>LOAD\"MENUVIC\",8 (VC20)<br>LOAD\"MENU264\",8 (C16,C116,plus\/4)<\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">Dadurch wird der Datei-Browser auf dem jeweiligen Computer gestartet. Nutze die Pfeiltasten, die R\u00fccktaste, die Eingabetaste oder den Joystick, um dich im Browser zu navigieren. \u00d6ffne Verzeichnisse und lade deine bevorzugten Spiele herunter. Verwende SHIFT + C, um die dargestellten Zeichen zu wechseln.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Disk wechseln<\/em><\/strong><br>Beispiel: Name des Spiels: LAZYJONES<br>&#8211; kopiere LAZYJONES1.D64 und LAZYJONES2.D64 auf die SD-Karte<br>&#8211; mache eine TXT-Datei mit<br>LAZYJONES1.D64<br>LAZYJONES2.D64<br>&#8211; speichere die Datei als LAZY.TXT (die Dateien und die TXT-Datei m\u00fcssen im gleichen Verzeichnis sein)<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">OPEN1,8,15,\"CD:NOMEDIR\":CLOSE 1\nOPEN1,8,15,\"XS:LAZY.txt\":CLOSE 1<\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn die blaue LED leuchtet, ist etwas schiefgegangen, wenn das blaue und das rote LED leuchten ist es OK.<br>LOAD&#8220;*&#8220;,8,1 oder LOAD&#8220;program.prg&#8220;,8,1 (verweist auf das D64 das in der TXT-Datei angegeben wurde: LAZYJONES1.D64)<br>und wenn angezeigt wird: &#8222;Disk wechseln&#8220;, einmal den Knopf &#8222;DISK&#8220; am C64SD dr\u00fccken, die rote und die blaue LED leuchten kurz und danach wird die zweite Disk gelesen (siehe blaue LED).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Andere Befehle<\/strong><\/em><br>Verzeichnisse wechseln:<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">OPEN1,8,15,\"CD\/SOMEDIR\/\":CLOSE1 - wechsele in das Verzeichnis \"SOMEDIR\" (relativ)\nOPEN1,8,15,\"CD\/\/\":CLOSE1 - wechsle in das ROOT-Verzeichnis\nOPEN1,8,15,\"CD\/\/SOMEDIR\/\":CLOSE1 - wechsle in das Verzeichnis \"SOMEDIR\" (im ROOT-Verzeichnis)\nOPEN1,8,15,\"CD:&lt;-\":CLOSE1 - wechsle in das Eltern-Verzeichnis (linker Pfeil)<\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">Benutzen von M2I oder D64 Dateien:<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">OPEN1,8,15,\"CD\/\/SOMEDR\/SOMEGAME.M2I\":CLOSE1 - wechsle zu SOMEGAME.M2I\nOPEN1,8,15,\"CD:&lt;-\":CLOSE1 - verlasse M2I Laden von Dateien\nLOAD\"\/\/SOMEDIR\/:SOMEFILE\" - lade die Datei \"SOMEFILE\" im Verzeichnis \"SOMEDIR\" (Dateinamen werden vom Pfad durch einen Doppelpunkt getrennt)<\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">MKDIR, RMDIR siehe README:<br>http:\/\/sd2iec.de\/cgi-bin\/gitweb.cgi?p=sd2iec.git;a=blob;f=README;hb=HEAD<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-4.jpg\" alt=\"C64SD V2.0 INFINITY - von vorne\" class=\"wp-image-2995\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-4.jpg 500w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-4-300x225.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption class=\"wp-element-caption\">C64SD V2.0 INFINITY &#8211; von vorne<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Firmware-Upgrade<\/strong><\/em><br>Die SD-Karte muss in FAT16 oder FAT32 formatiert sein.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lade die Firmware von http:\/\/www.sd2iec.de<\/li>\n\n\n\n<li>entpacke die Datei<\/li>\n\n\n\n<li>Kopiere die sd2iec.bin in das Root-Verzeichnis der SD-Karte<\/li>\n\n\n\n<li>schalte das SD2IEC aus &#8211; lege die Karte ein<\/li>\n\n\n\n<li>schalte das SD2IEC ein<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn das SD2IEC eingeschaltet wird, erkennt es eine andere als die aktuell verwendete Firmware. Die rote LED leuchtet, w\u00e4hrend die blaue LED f\u00fcr 8-10 Sekunden blinkt. Das Upgrade ist nun abgeschlossen! Um die Firmware-Version zu ermitteln, k\u00f6nnen Sie die Anweisungen auf der SD2IEC-Website befolgen:<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">LOAD\"C64SD.PRG,8,1 RUN<\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">oder<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">10 OPEN 1,8,15,\"UI\"<br>20 INPUT#1,FF$,FB$,SP$,SE$<br>30 PRINT FF$,FB$,SP$,SE$<br>40 CLOSE 1<br>RUN<br><br>oder<br>OPEN 1,8,15,\"UI\":FOR I=0 TO 2:POKE 58,1:GET#1,A$:PRINT A$;:I=255 AND ST:NEXT:CLOSE 1<\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">!kann nur verwendet werden, kurz nachdem das <strong>C64SD<\/strong> eingeschaltet wurde.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/nBJ8ly4uowg?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=en-GB&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/nBJ8ly4uowg\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Die erste Erweiterung f\u00fcr den C64 ist angekommen: ein SD-Kartenleser! Ich besitze bereits \u00e4hnliche Ger\u00e4te f\u00fcr Sinclair und Atari Computer. Beim C64 emuliert dieser haupts\u00e4chlich \u2026<\/p>","protected":false},"author":2,"featured_media":2994,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[115],"tags":[682,4737,4738],"class_list":["post-2967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c64","tag-commodore","tag-hardware","tag-how-to"],"wp-worthy-pixel":{"ignored":false,"public":"ffbc4b4691f8445086985415c1ccb74a","server":"","url":"https:\/\/vg08.met.vgwort.de\/na\/ffbc4b4691f8445086985415c1ccb74a"},"wp-worthy-type":"normal","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2013\/03\/C64-SD-Infinity-3.jpg","_links":{"self":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/2967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/comments?post=2967"}],"version-history":[{"count":2,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/2967\/revisions"}],"predecessor-version":[{"id":42662,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/2967\/revisions\/42662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media\/2994"}],"wp:attachment":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media?parent=2967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/categories?post=2967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/tags?post=2967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}