{"id":24887,"date":"2020-12-26T14:00:13","date_gmt":"2020-12-26T12:00:13","guid":{"rendered":"https:\/\/www.jungsi.de\/?p=24887"},"modified":"2026-08-28T10:40:00","modified_gmt":"2026-08-28T08:40:00","slug":"philips-odyssey-2001-pong-konsolen","status":"publish","type":"post","link":"https:\/\/www.jungsi.de\/en\/philips-odyssey-2001-pong-konsolen\/","title":{"rendered":"Philips Odyssey 2001 [Philips]"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Das Philips Odyssey ist ein Klassiker der Konsolen Historie und hat als Ursprung die Magnavox Odyssey aus dem Jahr 1972. Der Prototyp dieses Ger\u00e4ts wurde von 1966 bis 1968 von Ralph H. Baer u.&nbsp;a. entwickelt und Brown Box genannt. Der Arbeitgeber von Baer war der Milit\u00e4rzulieferer Sander Associates und nicht zur Vermarktung geeignet. Daher wurden z.B. mit General Electric und RCA Vertr\u00e4ge aufgesetzt, aber nie unterzeichnet. Ein ehemaliger RCA-Mitarbeiter der inzwischen bei Magnavox arbeitete, interessierte sich an die Brown Box, die von Sanders lizenziert, \u00fcberarbeitet und ab 1972 als Maganavox Odyssey vermarket wurde.<br>1974 wurde Magnavox dann von Philips aufgekauft und ver\u00f6ffentlichte im Zeitraum 1975 bis 1977 insgesamt acht verschiedene Spielkonsolen. Der Name der Konsole wurde in den USA nicht ge\u00e4ndert, in Europa wurden die Ger\u00e4te als Philips Odyssey vermarktet.<br>Bei meinem Ger\u00e4t handelt es sich um das Philips Odyssey 2001 das 1977 auf den Markt gekommen ist. Es handelt sich dabei um die Philips-Version der Magnavox-Odyssey 4000, wobei es Unterschiede in den Spielen gibt. Au\u00dferdem hatte die europ\u00e4ische Konsole abnehmbare Paddles (Drehkn\u00f6pfe) an Stelle von Joysticks.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Als Chip wird ein National Semiconductor MM-57105-Chip verwendet, der die Spiele Tennis, Hockey und Sqash enth\u00e4lt und Farbe sowie Ton unterst\u00fctzt. Im Gegensatz zu den meisten PONG-Spielen kam der Ton direkt aus dem Fernseher. Die Paddles sind fest verdrahtet, k\u00f6nnen also nicht abgenommen werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wird die Konsole ge\u00f6ffnet kann man sehen, dass die ganze Platine eigentlich auch in das Geh\u00e4use eines Gameboys gepasst h\u00e4tte. Das l\u00e4sst sich von au\u00dfen nicht vermuten. Die Unterseite ist lediglich mit einer &#8222;Schraube&#8220; die auch mit einer M\u00fcnze ge\u00f6ffnet werden kann.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24943\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-Box-1024x768.jpg\" alt=\"Odyssey 2001 - Box\" class=\"wp-image-24943\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-Box-1024x768.jpg 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-Box-300x225.jpg 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-Box.jpg 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Odyssey 2001 &#8211; Box<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24936\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-Anleitungen-1024x768.jpg\" alt=\"Odyssey 2001 - Anleitungen\" class=\"wp-image-24936\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-Anleitungen-1024x768.jpg 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-Anleitungen-300x225.jpg 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-Anleitungen.jpg 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Odyssey 2001 &#8211; Anleitungen<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Die Spielauswahl erfolgte einfach durch Dr\u00fccken der Taste eines der beiden Controller, sodass die Spieler von einem Spiel zum anderen wechseln konnten. Die Dokumentation dieser Konsole existiert in zehn Sprachen, obwohl nur vier ausl\u00e4ndische Patente auf der R\u00fcckseite des Systems abgebildet sind. Die genaue Anzahl der L\u00e4nder, in denen dieses System verkauft wurde, ist noch unbekannt. Dieses System ist recht verbreitet, und Deutschland scheint das Land zu sein, in dem es am erfolgreichsten war.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meiner Konsole, bei er zumindest der Originalkarton vorhanden ist, lag die Anleitung in acht verschiedenen Sprachen bei \u2013 ein beidseitig bedrucktes DIN-A4-Blatt.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24937\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-Paddle-1024x768.jpg\" alt=\"Odyssey 2001 - Paddle\" class=\"wp-image-24937\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-Paddle-1024x768.jpg 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-Paddle-300x225.jpg 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-Paddle.jpg 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Odyssey 2001 &#8211; Paddle<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"24940\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-seitlich-1024x768.jpg\" alt=\"Odyssey 2001\" class=\"wp-image-24940\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-seitlich-1024x768.jpg 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-seitlich-300x225.jpg 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001-seitlich.jpg 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Odyssey 2001<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tipp:<br>Das Netzteil ben\u00f6tigt 12V \u2013 innen plus \u2013 au\u00dfen minus<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alle die sich f\u00fcr die Anleitungen interessieren finden hier den Download:<\/p>\n\n\n    <a href=\"https:\/\/www.jungsi.de\/en\/?dl=philips-odyssey-2001-philips-24953\" class=\"dl-box\">\n        <span class=\"dl-box__icon\" aria-hidden=\"true\">\u2b07<\/span>\n        <span class=\"dl-box__info\">\n            <span class=\"dl-box__label\">Philips Odyssey 2001 - Anleitungen.zip<\/span>\n                            <span class=\"dl-box__meta\">51,99 MB<\/span>\n                    <\/span>\n        <span class=\"dl-box__count\">4978\u00d7<\/span>\n    <\/a>\n    \n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Aus der Originalanleitung<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Mit dem Odyssey 2001 haben Sie eines der aufregendsten Spiele der letzten Jahre erworben &#8211; ein Spiel, das Ihnen die Spannung des Sportplatzes ins Wohnzimmer bringt. Testen Sie Ihre Reaktionsgeschwindigkeit und die Ihrer Gegenspieler mit dem Odyssey 2001!<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em><strong>Die drei Spiele:&nbsp;<\/strong>EISHOCKEY, TENNIS UND SQUASH<\/em><br><em>Der Odyssey 2001 stellt eine Reihe spieltechnischer Anforderungen und besitzt aktionsf\u00f6rdernde Eigenschaften, die in jedem Spiel zur Geltung kommen:<\/em><\/li>\n\n\n\n<li><em>die Art des Spiels wird mit der Spiel-W\u00e4hltaste festgelegt; nach Druck auf die Taste erscheint die n\u00e4chste Spielart.<\/em><\/li>\n\n\n\n<li><em>jedes Spiel endet, wenn einer der Spieler 15 Punkte erreicht hat.<\/em><\/li>\n\n\n\n<li><em>durch Druck auf die Nullstelltaste kann die Punktanzeige wieder auf 0-0 gestellt werden.<\/em><\/li>\n\n\n\n<li><em>die Nullstelltaste dient auch zur Verkleinerung eines Spielers (beispielsweise, wenn die Spieler zu unterschiedliche Leistungen aufweisen oder um das Spiel spannender zu machen). Bewegen Sie zu diesem Zweck den Spieler, dessen Gr\u00f6\u00dfe ge\u00e4ndert werden soll, ganz nach oben und dr\u00fccken Sie dann die Nullstelltaste. Die Punktanzeige geht automatisch auf 0-0 zur\u00fcck.<\/em><\/li>\n\n\n\n<li><em>nachdem der Ball viermal von einem Spieler zur\u00fcckgespielt worden ist, ohne dass ein Punkt gegeben wurde, wird die Spielgeschwindigkeit automatisch erh\u00f6ht. Wenn nun ein Punkt gegeben wird, schaltet der Odyssey 2001 wieder auf die urspr\u00fcngliche Geschwindigkeit zur\u00fcck<\/em><\/li>\n\n\n\n<li><em>der Ton, der h\u00f6rbar wird, wenn Ball und Spieler zusammentreffen, kann mit dem Lautst\u00e4rkeregler des Fernsehempf\u00e4ngers eingestellt werden.<\/em><\/li>\n\n\n\n<li><em>wollen Sie allein spielen, m\u00fcssen Sie den blauen Knopf ganz nach links drehen. Dieser Spielerknopf ist dann ausgeschaltet. Die Spiel-W\u00e4hltaste kann aber weiter benutzt werden, und Sie spielen mit dem gr\u00fcnen Knopf \u2013 von der Stelle aus, wo der Spieler sich befindet, wird automatisch angegeben, und der Ball kommt vom Spieler selbst.<\/em><\/li>\n\n\n\n<li><em>der angebende Spieler kann bestimmen, wann der Ball ins Spiel kommen soll; solange der Spieler ganz nach oben gedreht ist, wird nicht angegeben.<\/em><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Das Philips Odyssey ist ein Klassiker der Konsolen Historie und hat als Ursprung die Magnavox Odyssey aus dem Jahr 1972. Der Prototyp dieses Ger\u00e4ts wurde \u2026<\/p>","protected":false},"author":2,"featured_media":24941,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[4824],"tags":[891],"class_list":["post-24887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-philips-odyssey-2001","tag-philips"],"wp-worthy-pixel":{"ignored":false,"public":"7e1a8ae8d528486198778bd9d5f21fdc","server":"","url":"https:\/\/vg06.met.vgwort.de\/na\/7e1a8ae8d528486198778bd9d5f21fdc"},"wp-worthy-type":"normal","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Odyssey-2001.jpg","_links":{"self":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/24887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/comments?post=24887"}],"version-history":[{"count":2,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/24887\/revisions"}],"predecessor-version":[{"id":43444,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/24887\/revisions\/43444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media\/24941"}],"wp:attachment":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media?parent=24887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/categories?post=24887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/tags?post=24887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}