{"id":21689,"date":"2019-03-03T18:00:18","date_gmt":"2019-03-03T17:00:18","guid":{"rendered":"https:\/\/www.jungsi.de\/?p=21689"},"modified":"2026-08-27T22:39:29","modified_gmt":"2026-08-27T20:39:29","slug":"procontroller-atari-jaguar","status":"publish","type":"post","link":"https:\/\/www.jungsi.de\/en\/procontroller-atari-jaguar\/","title":{"rendered":"ProController [Atari Jaguar]"},"content":{"rendered":"<figure id=\"attachment_22095\" aria-describedby=\"caption-attachment-22095\" style=\"width: 300px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-22095\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-2-300x225.jpg\" alt=\"Pro Controller\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-2-300x225.jpg 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-2-1024x768.jpg 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-2.jpg 1400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-22095\" class=\"wp-caption-text\">Pro Controller<\/figcaption><\/figure>\n<p>Der <em>ProController<\/em> ist eines der Dinge die ein Sammler des Atari Jaguar selten zu Gesicht bekommt &#8211; am wenigsten in Deutschland. Wenn doch, werden daf\u00fcr zwischen 100 und 150 \u20ac verlangt. Im Gegensatz zum normalen <em>Power Pad<\/em> ist dieser Controller wirklich besser. Leider nutzen nicht viele Spiele die zus\u00e4tzlichen Tasten, aber auch alle anderen Spiele lassen sich angenehmer damit spielen.<\/p>\n<p>Der Atari Jaguar <em>ProController<\/em> der erst im Oktober 1995 erschienen ist (der <em>Atari Jaguar<\/em> ist 1993 auf den Markt gekommen), bietet gegen \u00fcber <!--more-->dem <em>Power Pad<\/em> drei zus\u00e4tzliche Feuertasten (X, Y und Z) und zwei Schultertasten (L und R). Diese neuen Tasten werden \u00fcber die vorhandenen Zifferntasten zugeordnet.<\/p>\n<p>Taste 4 = linke Schultertaste<br \/>\nTaste 6 = rechte Schultertaste<br \/>\nTasten 7, 8, 9 = Z, Y, X<\/p>\n<p>Nur wenige Spiele wurden so programmiert, dass die zus\u00e4tzlichen Tasten unterst\u00fctzt werden &#8211; von Atari selbst gar nur vier: <em>Atari Karts, Battlemorph, Fight For Life <\/em>and<em> Missle Command 3D<\/em>. Es wird vermutet, das dieser Controller das <em>PowerPad<\/em> als Standardcontroller bei dem geplanten aber nicht mehr realisierten Jaguar Nachfolger &#8222;<em>Jaguar-Duo<\/em>&#8220; (<em>Jaguar<\/em> mit integrierten CD-Laufwerk) abl\u00f6sen sollte.<\/p>\n<figure id=\"attachment_22095-2\" aria-describedby=\"caption-attachment-22095-2\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-22095\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-2.jpg\" alt=\"Pro Controller\" width=\"650\" height=\"488\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-2.jpg 1400w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-2-300x225.jpg 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-2-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-22095-2\" class=\"wp-caption-text\">Pro Controller<\/figcaption><\/figure>\n<p>Ende November 2017 meldete sich im AtariAge-Forum ein Benutzer zu Wort, der bereits Erfahrung hat mit der Erstellung und Abwicklung von Ger\u00e4ten hatte. Er sammelte Interessenten f\u00fcr die Controller (Mindesatbnahmemenge 2 St\u00fcck) und wollte diese produzieren wenn sich ausreichend daf\u00fcr melden. Danach mussten u.a. die Gussformen erstellt werden. Im Dezember 2018 kamen meine Controller endlich an. Ich denke dass einige der n\u00e4chsten neuen Spiele, die f\u00fcr den Jaguar erscheinen werden, diesen Controller unterst\u00fctzen werden.<\/p>\n<p>Spiele, die den Jaguar <em>ProController<\/em> auch unterst\u00fctzen<br \/>\n<em>BattleSphere Gold<\/em><br \/>\n<em>BattleSphere<\/em><br \/>\n<em>Primal Rage<\/em><br \/>\n<em>Total Carnage<br \/>\nDownfall+<br \/>\nreBOOTed (erscheint demn\u00e4chst)<\/em><\/p>\n<p>Hier die am meisten gestellten Fragen aus dem AtariAge-Forum zu dem Controller<\/p>\n<p><em>Mit welchen \u200b\u200bSystemen arbeitet der Controller?<\/em><br \/>\nMit dem <em>Atari Jaguar<\/em>, <em>Atari STE<\/em> und dem <em>Atari Falcon<\/em> &#8211; mit einem Adapter funktioniert es auf den <em>Atari 2600-, Atari 8-Bit-, Atari ST-, Atari 5200-<\/em> und PC-Systemen.<\/p>\n<p><em>Was kosten die Controller?<\/em><br \/>\n60 $ pro Controller mit einer Mindestabnahme von 2 Controllern gleichzeitig<\/p>\n<p><em>Beinhaltet der Preis den Versand<\/em>?<br \/>\nIn den USA sollte der Versand f\u00fcr zwei Controller 5 $ betragen. Au\u00dferhalb der USA w\u00fcrde ein Paket mit zwei Controllern 21,14 $ Versand kosten.<\/p>\n<p><em>Wie bestelle ich die Controller?<\/em><br \/>\nE-Mail an Starwander@Comcast.net<br \/>\noder<br \/>\n<a href=\"https:\/\/hoskinson-industries.myshopify.com\/products\/atari-jaguar-pro-controller\" target=\"_blank\" rel=\"noopener\">Hoskinson Industries<\/a>&nbsp;bzw. im <a href=\"https:\/\/www.atariage.com\/store\/index.php?l=product_detail&amp;p=1192\" target=\"_blank\" rel=\"noopener\">Atari Age Store<\/a><\/p>\n<p><em>Wie wird die Qualit\u00e4t gesichert?<\/em><br \/>\nSobald die Form fertig war, wurden Muster zur Genehmigung versendet. Dies war die Gelegenheit, das Design zu verfeinern, bis das Produkt korrekt war.<\/p>\n<div id='gallery-1' class='gallery galleryid-21689 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.jungsi.de\/en\/procontroller-atari-jaguar\/pro-controller-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-3-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-1-22096\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-3-1024x768.jpg 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-3-300x225.jpg 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-3.jpg 1400w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-22096'>\n\t\t\t\tPro Controller &#8211; Schultertasten\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.jungsi.de\/en\/procontroller-atari-jaguar\/pro-controller-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-4-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"Pro Controller - Buttons\" aria-describedby=\"gallery-1-22097\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-4-1024x768.jpg 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-4-300x225.jpg 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Pro-Controller-4.jpg 1400w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-22097'>\n\t\t\t\tPro Controller &#8211; Buttons\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p><em>K\u00f6nnen zus\u00e4tzliche Funktionen wie USB-Kabel, Schnellfeuerfunktion oder Joystick hinzugef\u00fcgt werden<\/em><br \/>\nDas Ziel dieses Projekts war es, das Original wie geplant wieder herzustellen.<\/p>\n<p><em>Wird es das Atari Jaguar Logo haben?<\/em><br \/>\nNein, das Logo wird nicht angezeigt<\/p>\n<p><em>Ist es legal die Controller nachzubauen?<\/em><br \/>\nEs ist absolut legal, sie wieder herzustellen, da die Patente aufgrund des urspr\u00fcnglichen Hardware-Designs abgelaufen sind. Dies ist der Grund, warum Leute 1: 1-Klon-Systeme von <em>NES\/SNES<\/em> und so weiter machen.<\/p>\n<div class=\"wp_b_box\"><strong>Conclusion<\/strong><br \/>\nDie Qualit\u00e4t der Controller ist super &#8211; nun hat jeder Jaguar-Sammler die M\u00f6glichkeit den besten Controller zu nutzen. Ich hoffe das der Produzent viele <em>ProController<\/em> verkaufen kann und nicht zu einem Teil auf seinen Kosten sitzen bleibt.<\/div>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/-lXewE0Kwj8?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=en-GB&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/uZ89cIcx1G0?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=en-GB&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Der ProController ist eines der Dinge die ein Sammler des Atari Jaguar selten zu Gesicht bekommt &#8211; am wenigsten in Deutschland. Wenn doch, werden daf\u00fcr \u2026<\/p>","protected":false},"author":2,"featured_media":22092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[275],"tags":[668,1415,1414],"class_list":["post-21689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atari-jaguar","tag-atari","tag-power-pad","tag-procontroller"],"wp-worthy-pixel":{"ignored":false,"public":"dfe7493b7bf84aaf8a4c79deeb85fd35","server":"","url":"https:\/\/vg07.met.vgwort.de\/na\/dfe7493b7bf84aaf8a4c79deeb85fd35"},"wp-worthy-type":"normal","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/PowerPad-1.jpg","_links":{"self":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/21689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/comments?post=21689"}],"version-history":[{"count":1,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/21689\/revisions"}],"predecessor-version":[{"id":44716,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/21689\/revisions\/44716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media\/22092"}],"wp:attachment":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media?parent=21689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/categories?post=21689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/tags?post=21689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}