{"id":19056,"date":"2010-07-20T12:42:12","date_gmt":"2010-07-20T11:42:12","guid":{"rendered":"http:\/\/www.jungsi.de\/?p=19056"},"modified":"2017-12-27T12:48:16","modified_gmt":"2017-12-27T11:48:16","slug":"tag-10-vestkapp-norwegen","status":"publish","type":"post","link":"https:\/\/www.jungsi.de\/en\/tag-10-vestkapp-norwegen\/","title":{"rendered":"Tag 10: Vestkapp [Norwegen]"},"content":{"rendered":"<p style=\"text-align: justify;\">Ausflug zum Vestkapp<\/p>\n<p style=\"text-align: justify;\">Der \u00e4u\u00dfere Felsen auf 497 Metern hei\u00dft \u201cKjerringea\u201d und wird auch als \u201cVestkapp\u201d (Westkap) bezeichnet. Das Plateau ist Nord-Europas westlichstes Gebirgsplateau und liegt auf 62\u00b011\u201918\u201c n\u00f6rdlicher Breite und 5\u00b07\u201933\u201c \u00f6stlicher L\u00e4nge. Zum Vestkapp f\u00fchrt eine schmale Stra\u00dfe hinauf zu einem Parkplatz, von wo aus man weiter wandern oder einfach nur die herrliche Aussicht genie\u00dfen kann. Leider konnten wir auf Grund des schlechten Wetters die Aussicht nicht genie\u00dfen.<\/p>\n<p style=\"text-align: justify;\">Im anliegenden Vestkapphuset k\u00f6nnen Souvenire und kleine St\u00e4rkungen gekauft werden. Au\u00dferdem findet man rund um das Vestkapphuset einige Informationstafeln, die \u00fcber die Gegend, oder historische Ereignisse und Legenden wie die Folgenden berichten.<\/p>\n<p>ngg_shortcode_0_placeholder21<\/p>","protected":false},"excerpt":{"rendered":"<p>Ausflug zum Vestkapp Der \u00e4u\u00dfere Felsen auf 497 Metern hei\u00dft \u201cKjerringea\u201d und wird auch als \u201cVestkapp\u201d (Westkap) bezeichnet. Das Plateau ist Nord-Europas westlichstes Gebirgsplateau und \u2026<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[4,38,15],"tags":[1161,1172],"class_list":["post-19056","post","type-post","status-publish","format-standard","hentry","category-bikes","category-norwegen-2010","category-reisen","tag-norwegen","tag-vestkapp"],"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/19056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/comments?post=19056"}],"version-history":[{"count":0,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/19056\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media?parent=19056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/categories?post=19056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/tags?post=19056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}