{"id":16795,"date":"2019-04-02T18:00:53","date_gmt":"2019-04-02T17:00:53","guid":{"rendered":"http:\/\/www.jungsi.de\/?p=16795"},"modified":"2026-08-28T10:38:50","modified_gmt":"2026-08-28T08:38:50","slug":"strikeforce-philips-videopac","status":"publish","type":"post","link":"https:\/\/www.jungsi.de\/en\/strikeforce-philips-videopac\/","title":{"rendered":"Strikeforce [Philips Videopac]"},"content":{"rendered":"<figure id=\"attachment_13926\" aria-describedby=\"caption-attachment-13926\" style=\"width: 225px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-13926\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/philips-videopac-strikeforce-vorderseite-225x300.jpg\" alt=\"Strikeforce\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/philips-videopac-strikeforce-vorderseite-225x300.jpg 225w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/philips-videopac-strikeforce-vorderseite.jpg 600w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><figcaption id=\"caption-attachment-13926\" class=\"wp-caption-text\">Strikeforce<\/figcaption><\/figure>\n<p><strong>Strikeforce<\/strong><br \/>\n<strong>Autor:<\/strong> Revival Studios<br \/>\n<strong>Jahr:<\/strong> 2015<br \/>\n<strong>System:<\/strong> Videopac<br \/>\n<strong>Bezugsquelle:<\/strong> <a href=\"http:\/\/www.revival-studios.com\/videopac.php\" target=\"_blank\" rel=\"noopener noreferrer\">Shop<\/a><\/p>\n<p style=\"text-align: left;\">Dieses Spiel kommt&nbsp;aus Holland von den <em>Revival Studios<\/em>, die in der Szene keine Unbekannten sind. Das Modul mit dem passenden Aufkleber kommt in einer typischen <em>Videopac<\/em> Verpackung zusammen mit einem &#8222;Handbuch&#8220; das alle wichtigen Infos enth\u00e4lt. F\u00fcr die Besitzer eines <em>Videopac+<\/em> h\u00e4lt das Spiel hochaufl\u00f6sende Hintergrund-Grafiken bereit.<br \/>\nIm Spiel selbst, steuert der Spieler einen Kampfhubschrauber und muss diesen \u00fcber den Bildschirm bewegen. Das Ziel ist es die Panzer am Boden effektiv zu zerst\u00f6ren, w\u00e4hrend durch zwei Kampfflugzeuge Angriffe von oben und auch vom Panzer von unten erfolgen.<!--more--><br \/>\nMit dem&nbsp;Voice Add-On kann digitalisierter Sprache genossen werden. Durch das <a href=\"http:\/\/revival-studios.com\/highscores\/\" target=\"_blank\" rel=\"noopener noreferrer\">Internet Highscore System<\/a> gibt es einen Wettstreit mit Spielern aus der ganzen Welt \ud83d\ude42<\/p>\n<p style=\"text-align: left;\">Gespielt wird mit dem rechten Joystick. Dabei gilt es sowohl den Raketen der Kampfflugzeuge als auch des Panzers auszuweichen. Mit dem Knopf wird&nbsp;eine Rakete in Richtung Panzer abgeschossen. Wenn 10 Panzer zerst\u00f6rt wurden, geht es weiter zum n\u00e4chsten Level. Dabei gibt es 8 verschiedene Level Layouts zu erforschen.<\/p>\n<figure id=\"attachment_17324\" aria-describedby=\"caption-attachment-17324\" style=\"width: 225px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-17324\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/philips-videopac-strikeforce-modul-225x300.jpg\" alt=\"Philips Videopac - Strikeforce - Modul\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/philips-videopac-strikeforce-modul-225x300.jpg 225w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/philips-videopac-strikeforce-modul.jpg 600w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><figcaption id=\"caption-attachment-17324\" class=\"wp-caption-text\">Strikeforce &#8211; Modul<\/figcaption><\/figure>\n<p><strong>Internet Highscore<\/strong><br \/>\nNach jedem Spiel wird der Highscore angezeigt und ein Code. Mit diesem Code kann der Highscore auf der Internetseite der <em>Revival Studios<\/em> gespeichert werden.<\/p>\n<p><strong>Online Belohnungen<\/strong><br \/>\nNeben dem Erreichen eines Highscores, gibt es auch Belohnungen die f\u00fcr spezielle Aufgaben im Spiel verdient werden k\u00f6nnen.<\/p>\n<p>Das Spiel bietet folgende Belohnungen:<\/p>\n<p>[bronze] Rapid Reload &#8211; spiele 20 Spiele in einer Sitzung<br \/>\n[silver] Bullet Dodger &#8211; erreiche Level 4<br \/>\n[gold] Annhilator &#8211; alle Level abschlie\u00dfen<\/p>\n<p>Neben dem Hochladen der Highscores im Internet wie oben erw\u00e4hnt, ist es ebenso m\u00f6glich die verdienten Belohnungen online zu aktualisieren. Belohnungen werden zu den bereits erreichten, online gespeicherten addiert. Daher ist es nicht notwendig alle Belohnungen in einem einzigen Durchgang zu verdienen.<\/p>\n<div class=\"wp_b_box\"><strong>Fazit<\/strong><br \/>\nBesonders in der <em>Videopac+<\/em> Version ist das Spiel sehr bunt und macht einen tollen Eindruck. Leider ist es f\u00fcr mich gleich zu Beginn etwas zu schwer. Eine etwas gemilderter Scwhwierigkeitsgrad w\u00e4re f\u00fcr mich ausreichend gewesen um mehr Spass mit dem Spiel zu haben. Werde ich aber definitiv wieder spielen &#8211; nur um mich etwas zu verbessern &#8211; ein neuer Highscore ist doch immmer toll \ud83d\ude42<\/div>\n<div>&nbsp;<\/div>\n<div>\n<figure id=\"attachment_22342\" aria-describedby=\"caption-attachment-22342\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-22342\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Philips-Videopac-Strikeforce-Startscreen-1024x768.jpg\" alt=\"Philips Videopac - Strikeforce - Startscreen\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Philips-Videopac-Strikeforce-Startscreen-1024x768.jpg 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Philips-Videopac-Strikeforce-Startscreen-300x225.jpg 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Philips-Videopac-Strikeforce-Startscreen.jpg 1400w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-22342\" class=\"wp-caption-text\">Philips Videopac &#8211; Strikeforce &#8211; Startscreen<\/figcaption><\/figure>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Strikeforce Autor: Revival Studios Jahr: 2015 System: Videopac Bezugsquelle: Shop Dieses Spiel kommt&nbsp;aus Holland von den Revival Studios, die in der Szene keine Unbekannten sind. \u2026<\/p>","protected":false},"author":2,"featured_media":17324,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[734],"tags":[891,1001,1003,96,1002],"class_list":["post-16795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-philips-videopac-g7000","tag-philips","tag-philips-videopac","tag-revival-studios","tag-spiele","tag-strikeforce"],"wp-worthy-pixel":{"ignored":false,"public":"3e182bcf075c4874b830dcb0d89fcc56","server":"","url":"https:\/\/vg08.met.vgwort.de\/na\/3e182bcf075c4874b830dcb0d89fcc56"},"wp-worthy-type":"normal","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/philips-videopac-strikeforce-modul.jpg","_links":{"self":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/16795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/comments?post=16795"}],"version-history":[{"count":1,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/16795\/revisions"}],"predecessor-version":[{"id":44787,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/16795\/revisions\/44787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media\/17324"}],"wp:attachment":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media?parent=16795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/categories?post=16795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/tags?post=16795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}