{"id":14156,"date":"2016-07-24T17:38:53","date_gmt":"2016-07-24T16:38:53","guid":{"rendered":"http:\/\/www.jungsi.de\/?p=14156"},"modified":"2026-07-21T11:07:02","modified_gmt":"2026-07-21T09:07:02","slug":"deep-core-raider-sinclair-zx-spectrum","status":"publish","type":"post","link":"https:\/\/www.jungsi.de\/en\/deep-core-raider-sinclair-zx-spectrum\/","title":{"rendered":"Deep Core Raider [Sinclair ZX Spectrum]"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Deep Core Raider<\/strong><br><strong>Autor:<\/strong> Paul Jenkinson<br><strong>Jahr:<\/strong> 2016<br><strong>Rechner:<\/strong> Sinclair ZX Spectrum<br><a href=\"http:\/\/www.thespectrumshow.net\/spectrum-games.html\" target=\"_blank\" rel=\"noreferrer noopener\">Download<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieses Spiel funktioniert auf 48K Rechnern, aber nur mit eingeschr\u00e4nkten Sound. 48K mit AY Sound-Karte oder alle 128, +2 oder +3 Rechner werden mit AY Sound unterst\u00fctzt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Story<\/strong><br>Das Universum ist riesig, die Planeten und Monde sind zahlreich und die darin verborgenen Mineralien nahezu unbegrenzt.<br>Daher ist es kein Wunder, das fortgeschrittene Rassen den Wert dieser Waren hoch einsch\u00e4tzen und sich viele Individuen auf die Suche nach Reicht\u00fcmern machen.<br>Gro\u00dfe Firmen stehen in Konkurrenz zu kleinen Teams und Abenteurern um diese Himmelsk\u00f6rper zu finden und die Bodensch\u00e4tze abzubauen.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><br>Viele wurden schon vorher besucht und die von den gro\u00dfen Konzernen entdeckten sind mit Verteidigung \u00fcbers\u00e4t um ihre Investitionen zu sch\u00fctzen bis Ihre Bergbau-Teams eingetroffen sind.<\/p>\n\n\n<div class=\"wp-block-image wp-image-14318 size-full\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"355\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/deep-core-raider-screen.jpg\" alt=\"Deep Core Raider - Screen\" class=\"wp-image-14318\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/deep-core-raider-screen.jpg 474w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/deep-core-raider-screen-300x225.jpg 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption class=\"wp-element-caption\">Deep Core Raider &#8211; Screen<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr Individuen sind diese sehr gut bezahlt. Die ganze Auswertung und Forschung war erledigt und die Mineralien warten nur noch darauf abgeholt zu werden. Das geschieht, wenn man die Verteidigung passieren kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese kleine Art von Individuen, interstellare Piraten, Diebe, haben den Namen &#8222;Deep Core Raiders&#8220;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Das Spiel<\/strong><br>Steuere deinen Pod und navigiere tiefer zwischen die Planeten und sammle jedes Mineral das du finden kannst.<br>Achte auf die gemeinsame Verteidigung und wirf ein Auge auf deinen Treibstoff. Der Treibstoff kann in einigen H\u00f6hlen aufgef\u00fcllt werden.<br>Die Schwerkraft kann dein Freund sein, wenn du sie richtig einsetzt<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Steuerung<\/strong><br>Kempston-\/Sinclair-Joystick, Tastatur<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tastaturbelegung<br>Q &#8211; Feuer<br>O &#8211; links<br>P &#8211; rechts<br>SPACE &#8211; Bomben abwerfen<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Conclusion<\/strong><br>Ein wirklich nettes Spiel das etwas an Jetpac erinnert. Tipp: man kann etwas Sprit sparen wenn man die Schr\u00e4gen &#8222;runterrutscht&#8220;.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/smrqbI_dWHU?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=en-GB&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>Deep Core RaiderAutor: Paul JenkinsonJahr: 2016Rechner: Sinclair ZX SpectrumDownload Dieses Spiel funktioniert auf 48K Rechnern, aber nur mit eingeschr\u00e4nkten Sound. 48K mit AY Sound-Karte oder \u2026<\/p>","protected":false},"author":2,"featured_media":14319,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[102],"tags":[2400,666,96],"class_list":["post-14156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zx-spectrum","tag-review","tag-sinclair","tag-spiele"],"wp-worthy-pixel":{"ignored":false,"public":"e9d1e6ee3a0043f2a6793cc4cad63497","server":"","url":"https:\/\/vg08.met.vgwort.de\/na\/e9d1e6ee3a0043f2a6793cc4cad63497"},"wp-worthy-type":"normal","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/deep-core-raider-ladescreen.jpg","_links":{"self":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/14156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/comments?post=14156"}],"version-history":[{"count":1,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/14156\/revisions"}],"predecessor-version":[{"id":43651,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/14156\/revisions\/43651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media\/14319"}],"wp:attachment":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media?parent=14156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/categories?post=14156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/tags?post=14156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}