{"id":11583,"date":"2016-03-09T17:22:51","date_gmt":"2016-03-09T16:22:51","guid":{"rendered":"http:\/\/www.jungsi.de\/?p=11583"},"modified":"2026-08-28T11:24:59","modified_gmt":"2026-08-28T09:24:59","slug":"chroma-update-sinclair-zx81","status":"publish","type":"post","link":"https:\/\/www.jungsi.de\/en\/chroma-update-sinclair-zx81\/","title":{"rendered":"Chroma Update [Sinclair ZX81]"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Seit einiger Zeit gibt es von Paul Farrow ein Update f\u00fcr das Chroma Interface. Daf\u00fcr muss das Interface zu ihm eingesendet werden.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Was wurde aktualisiert?<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Das Update betrifft das <strong>ZX ROM Cartridge Generator Utility<\/strong>, das nun auch den <strong>ZX81<\/strong> unterst\u00fctzt. Damit k\u00f6nnen bis zu <strong>254 Programme und ROM-Dateien<\/strong> genutzt werden. Unterst\u00fctzt werden dabei die <strong>ZXC2, ZXC3 und ZXC4<\/strong>-Cartridges. Die Daten werden mit <strong>57.600 Baud<\/strong> auf den ZX81 geladen, der dann die ROM-Cartridge programmiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein besonderes Feature: F\u00fcr jede Datei in einer Zusammenstellung kann eine <strong>Farb-Datei<\/strong> zugewiesen werden. Diese wird als XML-Textdatei gespeichert und definiert die Farben f\u00fcr jeden Charakter. Dadurch wird es auch f\u00fcr Nicht-Programmierer m\u00f6glich, Spiele optisch anzupassen. Der <strong>Cartridge Creator<\/strong> sorgt dann daf\u00fcr, dass die Farben im RAM des Chroma gesetzt werden und das aktuelle Spiel geladen wird.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h5 class=\"wp-block-heading\">Entwicklung der Tools im \u00dcberblick<\/h5>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Chroma Program Enhancement Creator<\/strong><\/li>\n\n\n\n<li><strong>Chroma Character Generator utilities<\/strong><\/li>\n\n\n\n<li><strong>1. und 2. wurden zum Chroma Program Enhancement Generator Utility zusammengef\u00fchrt<\/strong><\/li>\n\n\n\n<li><strong>Chroma Program Enhancement Designer Utility<\/strong><\/li>\n\n\n\n<li><strong>3. und 4. wurden zum Chroma Program Enhancement Creator zusammengef\u00fchrt<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Der <strong>Chroma Program Enhancement Creator<\/strong> ist ein Windows-Tool, mit dem sich <strong>Ersatzzeichens\u00e4tze und Farbdefinitionen<\/strong> f\u00fcr ZX80- und ZX81-Programme erstellen lassen. Es generiert automatisch Ladeprogramme, die die Chroma-Schnittstelle vor dem Laden eines Spiels konfigurieren. Die Dateien lassen sich als <strong>.chr- oder .col-Dateien<\/strong> speichern und sp\u00e4ter erneut laden oder mit dem <strong>ZX ROM Cartridge Creator<\/strong> verwenden.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Hardware-Anpassungen<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Es zeigte sich, dass die <strong>Logik des Chroma Interface und des ZXC4 angepasst werden muss<\/strong>, um die Timing-Voraussetzungen f\u00fcr das Flash-ROM des ZXC4 zu erf\u00fcllen. Beim <strong>ZXC3<\/strong> ist das nicht notwendig, da es weniger Logik enth\u00e4lt und schneller reagiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich habe alle meine Interfaces (<strong>Chroma, SPECTRA und ZXC4<\/strong>) zu Paul geschickt und innerhalb kurzer Zeit zur\u00fcckerhalten \u2013 das alles f\u00fcr <strong>nur 8 Pfund<\/strong> (zzgl. Versand). Ein toller Service und immer ein netter Kontakt!<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/chroma-zxc4-menue.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/chroma-zxc4-menue.jpg\" alt=\"Chroma - ZXC4 Men\u00fc\" class=\"wp-image-11737\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/chroma-zxc4-menue.jpg 800w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/chroma-zxc4-menue-300x225.jpg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\">Chroma &#8211; ZXC4 Men\u00fc<\/figcaption><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\">Weiteres Update mit CHR$128-Support<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Ein weiteres Update f\u00fcr das Chroma Interface bringt nun die Unterst\u00fctzung f\u00fcr <strong>CHR$128 benutzerdefinierte Grafikmodi<\/strong>, bekannt von der <strong>UDG4ZXpand<\/strong>-Erweiterung. Obwohl dieser Modus urspr\u00fcnglich nicht zur Chroma-Spezifikation geh\u00f6rte, erm\u00f6glicht das Update die Nutzung aller wichtigen hochaufl\u00f6senden und UDG-Formate. Zudem verbessert sich die Toleranz f\u00fcr benutzerdefinierte Anzeigetreiber, die das Timing des Videoformats ver\u00e4ndern \u2013 etwa bei einigen <strong>1K-Spielen von Dr. Beep<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich finde das einfach super! Ich mag das <strong>UDG4ZXpand<\/strong> wegen seines guten Preis-Leistungs-Verh\u00e4ltnisses, aber jetzt kann ich diese M\u00f6glichkeiten auch mit dem <strong>Chroma Interface<\/strong> nutzen. F\u00fcr den neuen Modus muss lediglich <strong>DIP-Schalter 3 eingeschaltet<\/strong> werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit dem <strong>ZX ROM Cartridge Creator<\/strong> lassen sich jetzt <strong>UDG-CHR-Dateien<\/strong> den Spielen zuweisen, die dann automatisch geladen werden, wenn das Spiel von einer ZXC3- oder ZXC4-Cartridge gestartet wird. Der neue <strong>Chroma Program Enhancement Creator<\/strong> kann au\u00dferdem UDG-Dateien extrahieren und als <strong>.chr-Datei<\/strong> speichern.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/chroma-zxc4-spielemenue.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/chroma-zxc4-spielemenue.jpg\" alt=\"Chroma - ZXC4 Spielemen\u00fc\" class=\"wp-image-11736\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/chroma-zxc4-spielemenue.jpg 800w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/chroma-zxc4-spielemenue-300x225.jpg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\">Chroma &#8211; ZXC4 Spielemen\u00fc<\/figcaption><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\">Spiele mit Chroma-Support<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Auf der Seite <strong>Native Colour Programs<\/strong> sind viele neue Spiele hinzugekommen, die das Interface nutzen: <a href=\"http:\/\/www.fruitcake.plus.com\/Sinclair\/ZX81\/Chroma\/ChromaInterface_Software_NativeColour.htm#MonsterMaze\">http:\/\/www.fruitcake.plus.com\/Sinclair\/ZX81\/Chroma\/ChromaInterface_Software_NativeColour.htm#MonsterMaze<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wer sich dazu ein paar Videos anschauen m\u00f6chte, dem empfehle ich die <strong><a href=\"https:\/\/www.youtube.com\/playlist?list=PLnSS3x72KcggYfJOVAFurpZPvXUo-cOfl\" target=\"_blank\" rel=\"noreferrer noopener\">YouTube-Playlist <\/a>von Villordsutch<\/strong>!<\/p>","protected":false},"excerpt":{"rendered":"<p>Seit einiger Zeit gibt es von Paul Farrow ein Update f\u00fcr das Chroma Interface. Daf\u00fcr muss das Interface zu ihm eingesendet werden. Was wurde aktualisiert? \u2026<\/p>","protected":false},"author":2,"featured_media":8192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[43],"tags":[4737,4738,666],"class_list":["post-11583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zx81","tag-hardware","tag-how-to","tag-sinclair"],"wp-worthy-pixel":{"ignored":false,"public":"ff2e5390b2544076b36c13ee529bec5e","server":"","url":"https:\/\/vg04.met.vgwort.de\/na\/ff2e5390b2544076b36c13ee529bec5e"},"wp-worthy-type":"normal","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/2014\/11\/Chroma-Interface.jpg","_links":{"self":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/11583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/comments?post=11583"}],"version-history":[{"count":1,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/11583\/revisions"}],"predecessor-version":[{"id":43046,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/11583\/revisions\/43046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media\/8192"}],"wp:attachment":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media?parent=11583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/categories?post=11583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/tags?post=11583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}