{"id":10866,"date":"2018-05-30T18:00:21","date_gmt":"2018-05-30T17:00:21","guid":{"rendered":"http:\/\/www.jungsi.de\/?p=10866"},"modified":"2026-08-28T11:24:40","modified_gmt":"2026-08-28T09:24:40","slug":"zx80core-sinclair","status":"publish","type":"post","link":"https:\/\/www.jungsi.de\/en\/zx80core-sinclair\/","title":{"rendered":"ZX80CORE [Sinclair ZX81]"},"content":{"rendered":"<p class=\"has-text-align-left wp-block-paragraph\">Keine Ahnung warum ich bisher zu diesem kleinen Schmuckst\u00fcck noch nichts geschrieben hatte. Das Ger\u00e4t habe ich schon seid 2013 und damit seid der ersten Auflage. \ud83d\ude42<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hintergrund<\/strong><br>Wie dem Namen schon zu entnehmen ist, hat das Projekt mit dem Sinclair ZX80 zu tun. Dieser erschien 1980 als einer der ersten Heimcomputer f\u00fcr den Massenmarkt. Als Prozessor wurde der schon bekannte Z80 mit 3,25 MHz Taktfrequenz verwendet und hatte 4 kB ROM, 1 kB RAM und wurde in BASIC programmiert.<br>Im ersten Jahr wurden von dem Rechner ca. 50.000 Exemplare verkauft und er kostete als Bausatz unter 80 Pfund bzw. als&nbsp;Fertigger\u00e4t 100 Pfund.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><br>Bereits ein Jahr sp\u00e4ter gab es dann den Sinclair ZX81, der schon 8kB ROM hatte und bessere Rechenleistungen bieten konnte. Da der ZX80 w\u00e4hrend der Berechnungen oder des Programmablaufs keine Bildausgabe hatte (nicht mal bei Tastatureingaben), flackerte das Bild bei jedem Tastendruck. Das wurde beim ZX81 durch Einf\u00fchrung des Slow-Modus eliminiert &#8211;&nbsp; dadurch konnte dieser gleichzeitig rechnen und die Bildausgabe erledigen. Vom ZX81 wurden ca. 1 Million St\u00fcck verkauft.<br>Auf Grund der Seltenheit des Rechners erzielt der ZX80 heute aber bis zu 300 \u20ac f\u00fcr gut erhaltene Modelle.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Der ZX80CORE wurde von dem Entwickler\/T\u00fcftler Pokemon umgesetzt. Das Board gab es komplett fertig aufgebaut oder ganz klassisch als Bausatz auf <a href=\"https:\/\/www.sellmyretro.com\/\" target=\"_blank\" rel=\"noopener\">SellMyRetro<\/a> oder \u00fcber das deutsche <a href=\"http:\/\/forum.tlienhard.com\/phpBB3\/\" target=\"_blank\" rel=\"noopener\">ZX Team Forum<\/a>.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Damit auch Nichtsammler in den Genuss eines ZX80 kommen, wurde diese Replik um zus\u00e4tzliche F\u00e4higkeiten erweitert. Der ZX80CORE wurde auf Basis des Originalschaltplans entwickelt, bietet aber auch einige moderne Optionen.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-autoplay=\"true\" data-delay=\"5\" data-effect=\"slide\" style=\"--aspect-ratio:calc(720 \/ 540)\"><div class=\"wp-block-jetpack-slideshow_container swiper\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"ZX80CORE - obere H\u00e4lfte\" class=\"wp-block-jetpack-slideshow_image wp-image-20126\" data-id=\"20126\" data-aspect-ratio=\"720 \/ 540\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-obere-H\u00e4lfte-1024x768.jpg\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-obere-H\u00e4lfte-1024x768.jpg 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-obere-H\u00e4lfte-300x225.jpg 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-obere-H\u00e4lfte.jpg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">ZX80CORE &#8211; obere H\u00e4lfte<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"ZX80CORE - Anschl\u00fcsse\" class=\"wp-block-jetpack-slideshow_image wp-image-41895\" data-id=\"41895\" data-aspect-ratio=\"720 \/ 540\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Anschluesse-1024x768.webp\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Anschluesse-1024x768.webp 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Anschluesse-300x225.webp 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Anschluesse-16x12.webp 16w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Anschluesse.webp 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">ZX80CORE &#8211; Anschl\u00fcsse<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"ZX80CORE - Interfaceport\" class=\"wp-block-jetpack-slideshow_image wp-image-41896\" data-id=\"41896\" data-aspect-ratio=\"720 \/ 540\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Interfaceport-1024x768.webp\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Interfaceport-1024x768.webp 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Interfaceport-300x225.webp 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Interfaceport-16x12.webp 16w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Interfaceport.webp 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">ZX80CORE &#8211; Interfaceport<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"ZX80CORE - NMI\" class=\"wp-block-jetpack-slideshow_image wp-image-41897\" data-id=\"41897\" data-aspect-ratio=\"720 \/ 540\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-NMI-1024x768.webp\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-NMI-1024x768.webp 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-NMI-300x225.webp 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-NMI-16x12.webp 16w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-NMI.webp 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">ZX80CORE &#8211; NMI<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"ZX80CORE - NMI_2\" class=\"wp-block-jetpack-slideshow_image wp-image-41898\" data-id=\"41898\" data-aspect-ratio=\"720 \/ 540\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-NMI_2-1024x768.webp\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-NMI_2-1024x768.webp 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-NMI_2-300x225.webp 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-NMI_2-16x12.webp 16w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-NMI_2.webp 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">ZX80CORE &#8211; NMI_2<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" alt=\"ZX80CORE - R\u00fcckseite\" class=\"wp-block-jetpack-slideshow_image wp-image-41899\" data-id=\"41899\" data-aspect-ratio=\"720 \/ 960\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Rueckseite-768x1024.webp\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Rueckseite-768x1024.webp 768w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Rueckseite-225x300.webp 225w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Rueckseite-9x12.webp 9w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">ZX80CORE &#8211; R\u00fcckseite<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"ZX80CORE - Tastatur\" class=\"wp-block-jetpack-slideshow_image wp-image-41900\" data-id=\"41900\" data-aspect-ratio=\"720 \/ 540\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Tastatur-1024x768.webp\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Tastatur-1024x768.webp 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Tastatur-300x225.webp 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Tastatur-16x12.webp 16w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-Tastatur.webp 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">ZX80CORE &#8211; Tastatur<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"ZX80CORE - ZX8-CCB\" class=\"wp-block-jetpack-slideshow_image wp-image-41901\" data-id=\"41901\" data-aspect-ratio=\"720 \/ 540\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-ZX8-CCB-1024x768.webp\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-ZX8-CCB-1024x768.webp 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-ZX8-CCB-300x225.webp 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-ZX8-CCB-16x12.webp 16w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-ZX8-CCB.webp 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">ZX80CORE &#8211; ZX8-CCB<\/figcaption><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>NMI Generator ZX80NMIX<\/li>\n\n\n\n<li>Video Modul ZX8CCB<\/li>\n\n\n\n<li>ROM Switch zur Umschaltung von Betriebssystemen (ZX80\/ZX81\/Forth\/&#8230;)<\/li>\n\n\n\n<li>ZX80IKIT &#8211; programmgesteuerte LED Beleuchtung abh\u00e4ngig von der Nutzung des Computers<\/li>\n\n\n\n<li>ROM erweiterbar auf 8 oder 16 kByte, bis 64 kByte umschaltbar<\/li>\n\n\n\n<li>RAM erweiterbar auf 16 kByte<\/li>\n\n\n\n<li>Folientastatur &#8211; oder SMD Taster<\/li>\n\n\n\n<li>Bildausgabe \u00fcber Video\/Chinch<\/li>\n\n\n\n<li>Video: BAS-Video \/ Composite Video<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Programme k\u00f6nnen nat\u00fcrlich wie fr\u00fcher per Kassette geladen und gespeichert werden. Nat\u00fcrlich funktioniert auch ein modernes Medium wie z.B. das ZXpand.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit dem ROM-Schalter kann zwischen folgenden ROMs gew\u00e4hlt werden<br>Schalter 0: ZX81 ROM 8k<br>Schalter 2: ZX80 ROM 4k<br>Schalter 3: UDG Char<br>Schalter 4: H4TH ROM 8k<br>Schalter 5: ASZMIC ROM 4k<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das wirklich gelungene Design mit der wei\u00dfen Platine und den Extras wie dem Ilumination-Kit und dem sp\u00e4ter erschienen Acryl-Geh\u00e4use machen diesen Rechner zu einem echten Hingucker! Der Aufwand der hier betrieben wurde ist schon extrem. Besucher des j\u00e4hrlichen Treffen des ZX-Teams in Mahlerts k\u00f6nnen den Entwickler pers\u00f6nlich kennen lernen.<br>Beim&nbsp;Treffen 2015 wurde bereits der &#8222;Nachfolger&#8220; des ZX80CORE als Prototyp vorgestellt &#8211; der ZXmore! \ud83d\ude42<\/p>","protected":false},"excerpt":{"rendered":"<p>Keine Ahnung warum ich bisher zu diesem kleinen Schmuckst\u00fcck noch nichts geschrieben hatte. Das Ger\u00e4t habe ich schon seid 2013 und damit seid der ersten \u2026<\/p>","protected":false},"author":2,"featured_media":20126,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[43],"tags":[4737,666],"class_list":["post-10866","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zx81","tag-hardware","tag-sinclair"],"wp-worthy-pixel":{"ignored":false,"public":"44e536548d2340158a667317ab42bf9b","server":"","url":"https:\/\/vg08.met.vgwort.de\/na\/44e536548d2340158a667317ab42bf9b"},"wp-worthy-type":"normal","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/ZX80CORE-obere-H\u00e4lfte.jpg","_links":{"self":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/10866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/comments?post=10866"}],"version-history":[{"count":4,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/10866\/revisions"}],"predecessor-version":[{"id":42750,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/10866\/revisions\/42750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media\/20126"}],"wp:attachment":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media?parent=10866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/categories?post=10866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/tags?post=10866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}