{"id":24549,"date":"2020-08-07T13:05:30","date_gmt":"2020-08-07T11:05:30","guid":{"rendered":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Neo-Geo-AES-Arcade-Controller-seitlich.jpg"},"modified":"2020-08-07T13:11:51","modified_gmt":"2020-08-07T11:11:51","slug":"neo-geo-aes-arcade-controller-seitlich","status":"inherit","type":"attachment","link":"https:\/\/www.jungsi.de\/en\/neo_geo_aes_snk\/neo-geo-aes-arcade-controller-seitlich\/","title":{"rendered":"Arcade Controller"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"_links_to":"","_links_to_target":""},"class_list":["post-24549","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Neo-Geo-AES-Arcade-Controller-seitlich.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Neo-Geo-AES-Arcade-Controller-seitlich-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"Arcade Controller\" srcset=\"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Neo-Geo-AES-Arcade-Controller-seitlich-300x225.jpg 300w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Neo-Geo-AES-Arcade-Controller-seitlich-1024x768.jpg 1024w, https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Neo-Geo-AES-Arcade-Controller-seitlich.jpg 1400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Arcade Controller<\/p>\n"},"caption":{"rendered":"<p>Arcade Controller<\/p>\n"},"alt_text":"Arcade Controller","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1400,"height":1050,"file":"Neo-Geo-AES-Arcade-Controller-seitlich.jpg","filesize":160666,"sizes":{"medium":{"file":"Neo-Geo-AES-Arcade-Controller-seitlich-300x225.jpg","width":300,"height":225,"filesize":28277,"mime_type":"image\/jpeg","source_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Neo-Geo-AES-Arcade-Controller-seitlich-300x225.jpg"},"large":{"file":"Neo-Geo-AES-Arcade-Controller-seitlich-1024x768.jpg","width":1024,"height":768,"filesize":92557,"mime_type":"image\/jpeg","source_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Neo-Geo-AES-Arcade-Controller-seitlich-1024x768.jpg"},"neve-blog":{"file":"Neo-Geo-AES-Arcade-Controller-seitlich-930x620.jpg","width":930,"height":620,"filesize":73268,"mime_type":"image\/jpeg","source_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Neo-Geo-AES-Arcade-Controller-seitlich-930x620.jpg"},"full":{"file":"Neo-Geo-AES-Arcade-Controller-seitlich.jpg","width":1400,"height":1050,"mime_type":"image\/jpeg","source_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Neo-Geo-AES-Arcade-Controller-seitlich.jpg"}},"image_meta":{"aperture":"3.5","credit":"","camera":"Canon PowerShot SX260 HS","caption":"","created_timestamp":"1576336875","copyright":"","focal_length":"4.5","iso":"1600","shutter_speed":"0.05","title":"","orientation":"1","keywords":[]}},"post":23759,"source_url":"https:\/\/www.jungsi.de\/blog\/wp-content\/uploads\/Neo-Geo-AES-Arcade-Controller-seitlich.jpg","filename":"Neo-Geo-AES-Arcade-Controller-seitlich.jpg","filesize":160666,"_links":{"self":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media\/24549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/comments?post=24549"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":23759,"href":"https:\/\/www.jungsi.de\/en\/wp-json\/wp\/v2\/posts\/23759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}